{"id":7899,"date":"2018-04-09T00:00:00","date_gmt":"2018-04-08T22:00:00","guid":{"rendered":"http:\/\/chromatique.net\/index.php\/2020\/04\/01\/7899"},"modified":"2018-04-09T00:00:00","modified_gmt":"2018-04-08T22:00:00","slug":"7899","status":"publish","type":"post","link":"https:\/\/www.chromatique.net\/index.php\/2018\/04\/09\/7899\/","title":{"rendered":"Phi &#8211; Cycles"},"content":{"rendered":"\n<p>Phi a vu le jour en Autriche, en l&rsquo;an de gr\u00e2ce 2011. Leurs albums sont fortement ancr\u00e9s dans un usage \u00e0 l\u2019anglaise du <em>Crossover Prog<\/em>. Le groupe se compose, de nos jours, de quatre musiciens, dans une \u00e9quipe recycl\u00e9e, form\u00e9e \u00e0 la fois de fondateurs et de nouveaux membres. <em>Cycles<\/em>, quatri\u00e8me album en date, porte en cela un nom coordonn\u00e9 aux mouvements fluctuants du <em>line-up<\/em> et aux virevoltes de la musique. <br \/><br \/> L\u2019aventure d\u00e9bute par une introduction pluvieuse au milieu d\u2019\u00e9chos maritimes\u2026 Puis un riff massif perfore l&rsquo;atmosph\u00e8re, et le chant entre en jeu, au fil de couplets magn\u00e9tiques et de refrains plus imposants. Le son est souvent gras et satur\u00e9, tel qu&rsquo;on peut l\u2019entendre dans le <em>djent<\/em>. Tout \u00e7a tourne comme sur des roulettes et les titres fluctuent entre \u00e9claircies diablement m\u00e9lodiques et grosses rythmiques saccad\u00e9es d\u2019une puissance captivante. Les atmosph\u00e8res sont charg\u00e9es, presque tendues, fr\u00e9quent\u00e9es de soli torrides. L\u2019infrastructure basse \/ batterie pilonne presque sans rel\u00e2che, bien charpent\u00e9e et ind\u00e9fectible. On ressent ici l\u2019inspiration de la caract\u00e9ristique la plus teigneuse de Porcupine Tree ou de The Pineapple Thief. En effet, nous sommes dans un genre assez proche, n\u00e9anmoins, une signature musicale particuli\u00e8re et un son personnel permettent de faire une diff\u00e9rence tr\u00e8s appr\u00e9ciable. <br \/><br \/> Phi s\u2019affirme de disque en disque, et m\u00eame si les pr\u00e9c\u00e9dents \u00e9taient d\u00e9j\u00e0 remarquables, voire plus sophistiqu\u00e9s, ce dernier semble \u00eatre \u00e0 l&rsquo;apog\u00e9e de leur discographie, tant sur le plan de l&rsquo;inspiration que de la finition.<\/p>","protected":false},"excerpt":{"rendered":"<p>Phi a vu le jour en Autriche, en l&rsquo;an de gr\u00e2ce 2011. Leurs albums sont&#8230;<\/p>\n","protected":false},"author":48,"featured_media":7900,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[38,24],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/7899"}],"collection":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/comments?post=7899"}],"version-history":[{"count":0,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/7899\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media\/7900"}],"wp:attachment":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media?parent=7899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/categories?post=7899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/tags?post=7899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}