{"id":7841,"date":"2017-12-12T00:00:00","date_gmt":"2017-12-11T23:00:00","guid":{"rendered":"http:\/\/chromatique.net\/index.php\/2020\/04\/01\/7841"},"modified":"2017-12-12T00:00:00","modified_gmt":"2017-12-11T22:00:00","slug":"7841","status":"publish","type":"post","link":"https:\/\/www.chromatique.net\/index.php\/2017\/12\/12\/7841\/","title":{"rendered":"Onefoot &#8211; Mektonized"},"content":{"rendered":"\n<p><em>Mektonized<\/em> est le premier album du groupe Onefoot form\u00e9 par trois jeunes musiciens virtuoses marseillais : Yessa\u00ef Karapetian (claviers et piano), Marc Karapetian (basse) et Matthieu Font (batterie). <br \/><br \/> Une \u00e9coute superficielle des premi\u00e8res minutes disque pourrait donner l\u2019impression que les Fran\u00e7ais appartiennent au monde des musiques \u00e9lectroniques avec une pr\u00e9dominance de synth\u00e9tiseurs modernes et vintage (notons la pr\u00e9sence du Sega SID Mekto-System un appareil qui g\u00e9n\u00e8re des sons 8 bits construit par le batteur \u00e0 partir de consoles Commodore 64 et Master System). Influenc\u00e9 par des formations comme Daft Punk ou Justice et la sc\u00e8ne <em>dubstep<\/em>, Onefoot poss\u00e8de n\u00e9anmoins une solide formation jazz que l\u2019on retrouve au long de l\u2019album, \u00e0 la fois par certaines touches subtiles (les rythmiques syncop\u00e9es de Matthieu Font) mais aussi au premier plan, notamment quand Yessa\u00ef Karapetian troque ses synth\u00e9s pour un piano virevoltant (\u00ab\u00a0Mektonized\u00a0\u00bb). Si cet assemblage post-moderne d\u2019influences \u00e9voque la d\u00e9marche d\u2019un groupe comme <a href=\"http:\/\/chromatique.net\/chroniques\/item\/16154-diabolicus-felinae-pandemonium\">Pryapisme<\/a> (dont la Chromateam est fan depuis quelques ann\u00e9es d\u00e9j\u00e0), Onefoot d\u00e9passe le simple collage iconoclaste gr\u00e2ce \u00e0 une attention particuli\u00e8re port\u00e9e sur les m\u00e9lodies. Enfin, <em>Mekltonized<\/em> est aussi transcend\u00e9 par la tradition arm\u00e9nienne, les trois membres s\u2019\u00e9tant rencontr\u00e9s dans un orchestre d\u00e9di\u00e9 \u00e0 ces musiques. On en retrouve la trace par la pr\u00e9sence du pogh (fl\u00fbte arm\u00e9nienne) sur certains morceaux (\u00ab\u00a0Fallen Angel\u00a0\u00bb) mais aussi de fa\u00e7on plus discr\u00e8te au travers du disque, avec l\u2019utilisation dans l\u2019\u00e9criture de la modalit\u00e9 arm\u00e9nienne.<br \/><br \/> La r\u00e9union de tous ces \u00e9l\u00e9ments pourrait laisser penser que la musique de Onefoot manque de coh\u00e9rence; il n\u2019en est rien. Le trio parvient \u00e0 garder une  homog\u00e9n\u00e9it\u00e9 qui rend le disque tout \u00e0 fait fluide. L\u2019album \u00e9voque la po\u00e9sie d\u2019un monde r\u00e9tro-futuriste \u00e0 la fois inqui\u00e9tant et fascinant, son c\u00f4t\u00e9 accrocheur et imm\u00e9diat d\u00e9voile de nombreuses subtilit\u00e9 au fil des \u00e9coutes. Un peu \u00e0 la mani\u00e8re du projet <a href=\"chroniques\/item\/14773-mehliana-taming-the-dragon\"> Mehliana<\/a>, Onefoot parvient \u00e0 d\u00e9passer brillamment la somme de ses influences pour offrir une exp\u00e9rience sonore tout \u00e0 fait personnelle et pertinente, une r\u00e9ussite de plus dans la sc\u00e8ne jazz fran\u00e7aise.<\/p>","protected":false},"excerpt":{"rendered":"<p>Mektonized est le premier album du groupe Onefoot form\u00e9 par trois jeunes musiciens virtuoses marseillais&#8230;<\/p>\n","protected":false},"author":46,"featured_media":7842,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[70,33],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/7841"}],"collection":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/comments?post=7841"}],"version-history":[{"count":0,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/7841\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media\/7842"}],"wp:attachment":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media?parent=7841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/categories?post=7841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/tags?post=7841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}