{"id":7831,"date":"2017-11-19T00:00:00","date_gmt":"2017-11-18T23:00:00","guid":{"rendered":"http:\/\/chromatique.net\/index.php\/2020\/04\/01\/7831"},"modified":"2017-11-19T00:00:00","modified_gmt":"2017-11-18T22:00:00","slug":"7831","status":"publish","type":"post","link":"https:\/\/www.chromatique.net\/index.php\/2017\/11\/19\/7831\/","title":{"rendered":"Franck M\u00e9dioni &#8211; Sounds of Surprise \u2013 Le jazz en 100 disques"},"content":{"rendered":"\n<p>Journaliste, homme de radio et auteur de nombreux livres (sur Jimi Hendrix, Miles Davis, Django Reinhardt&#8230;), Franck M\u00e9dioni est surtout connu pour sa contribution \u00e0 Jazz Magazine et \u00e0 l&rsquo;\u00e9mission Jazzistiques sur France Musiques. C&rsquo;est dire s&rsquo;il ma\u00eetrise son sujet. S\u00e9lectionner cent disques dans un genre aussi multiple n&rsquo;a pas d\u00fb \u00eatre chose ais\u00e9e, <em>a fortiori<\/em> pour quelqu&rsquo;un qui en conna\u00eet un rayon en la mati\u00e8re. <br \/><br \/> Plut\u00f4t que d&rsquo;essayer vainement de d\u00e9finir cette musique aux formes si nombreuses, M\u00e9dioni emprunte les mots de <em>jazzmen<\/em> \u00e0 qui l&rsquo;on posait la question. Devant l&rsquo;impossibilit\u00e9 de donner une d\u00e9finition satisfaisante, il conclut : le jazz, c&rsquo;est avant tout une clameur. Contrairement \u00e0 d&rsquo;autres ouvrages de la collection, il n&rsquo;y a pas de tentative de sa part de convaincre \u00e0 l&rsquo;aide d&rsquo;arguments qui se voudraient objectifs. Il d\u00e9crit les \u0153uvres avec son ressenti, dans un langage souvent m\u00e9taphorique, et de la plume adroite qu&rsquo;on lui conna\u00eet. Les \u00e9motions priment sur les aspects purement factuels comme le succ\u00e8s ou l&rsquo;influence, m\u00eame si ceux-ci sont naturellement \u00e9voqu\u00e9s et analys\u00e9s. Et lorsqu&rsquo;il aborde l&rsquo;in\u00e9vitable historique du genre, M\u00e9dioni le fait avec un style qui lui est propre, en racontant le jazz comme une \u00e9pop\u00e9e, nourrie des grandes aspirations artistiques de ses h\u00e9ros. <br \/><br \/> La s\u00e9lection des cent albums se porte en grande partie (les deux tiers environ) sur les d\u00e9cennies qui ont amen\u00e9 de grands bouleversements dans le jazz &#8211; mais bien apr\u00e8s l&rsquo;apparition de la r\u00e9volution be-bop &#8211; \u00e0 savoir les ann\u00e9es cinquante \u00e0 soixante-dix  : jazz cool, hardbop, jazz fusion, free jazz&#8230;cette p\u00e9riode est riche en rebondissements et on ne peut d\u00e9cemment s&rsquo;offusquer de son h\u00e9g\u00e9monie dans les choix de l&rsquo;auteur, tant elle a donn\u00e9 naissance \u00e0 des chefs d\u2019\u0153uvre comme ceux de Miles Davis, Charles Mingus, Sonny Rollins, Thelonious Monk, Dave Brubeck, Chet Baker, Stan Getz, John Coltrane, Herbie Hancock, Chick Corea, Sun Ra et tellement d&rsquo;autres. Mais si les grands noms sont tous l\u00e0, M\u00e9dioni place aussi quelques artistes moins universellement connus qui ont ses faveurs. Le tout forme un bel \u00e9quilibre, entre consensus et contre-pied.<br \/><br \/> Comme toute anthologie, celle-ci peut \u00eatre discut\u00e9e. On comprend \u00e0 la fois la pr\u00e9dominance d&rsquo;un certain  ge d&rsquo;Or du jazz en d\u00e9plorant en m\u00eame temps le peu de repr\u00e9sentants d&rsquo;une sc\u00e8ne actuelle pourtant infiniment riche et en constant renouvellement. <em>Sounds of Surprise<\/em> reste avant tout un outil de d\u00e9couverte \u00e9crit par un auteur passionn\u00e9 et comp\u00e9tent, et \u00e0 ce titre, il remplit totalement son r\u00f4le.<\/p>","protected":false},"excerpt":{"rendered":"<p>Journaliste, homme de radio et auteur de nombreux livres (sur Jimi Hendrix, Miles Davis, Django&#8230;<\/p>\n","protected":false},"author":14,"featured_media":7832,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[141,33],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/7831"}],"collection":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/comments?post=7831"}],"version-history":[{"count":0,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/7831\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media\/7832"}],"wp:attachment":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media?parent=7831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/categories?post=7831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/tags?post=7831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}