{"id":7583,"date":"2016-12-16T00:00:00","date_gmt":"2016-12-15T23:00:00","guid":{"rendered":"http:\/\/chromatique.net\/index.php\/2020\/04\/01\/7583"},"modified":"2016-12-16T00:00:00","modified_gmt":"2016-12-15T22:00:00","slug":"7583","status":"publish","type":"post","link":"https:\/\/www.chromatique.net\/index.php\/2016\/12\/16\/7583\/","title":{"rendered":"Antoine Fafard &#8211; Sphere"},"content":{"rendered":"\n<p>La fusion jazz \u00ab\u00a0spatiale\u00a0\u00bb &#8211; il faut bien trouver un nom \u00e0 une branche peu fournie d&rsquo;un genre par ailleurs pl\u00e9thorique &#8211; est une tr\u00e8s lointaine descendante de Return To Forever et autres Mahavishnu Orchestra, p\u00e9trie d&rsquo;influences progressives. Cette modeste mouvance a b\u00e9n\u00e9fici\u00e9 d&rsquo;une relative exposition dans les ann\u00e9es quatre-vingt dix et deux mille gr\u00e2ce \u00e0 des groupes comme Planet X, Special Providence &#8211; qui en repr\u00e9sente la version la plus \u00e9nerv\u00e9e &#8211; ou encore Spaced Out, ce dernier s&rsquo;\u00e9tant dissolu apr\u00e8s <a href=\"chroniques\/item\/1933-Evolution\" target=\"\u201d_blank\u201d\"><em>Evolution<\/em><\/a>, un ultime album qui n&rsquo;a que moyennement convaincu. Son bassiste Antoine Fafard tente depuis quatre disques en solo d&rsquo;entretenir une flamme dont on ne sait pas vraiment si elle est encore \u00e0 m\u00eame de dispenser quelque chaleur. Aux c\u00f4t\u00e9s du guitariste Jerry De Villiers Jr et du batteur Gary Husband, Fafard remet donc le couvert avec <em>Sphere<\/em> pour essayer de nous convaincre du bien-fond\u00e9 de sa pers\u00e9v\u00e9rance. Le tr\u00e8s canonique \u00ab\u00a0Reminiscence\u00a0\u00bb d&rsquo;ouverture et le \u00ab\u00a0Renaissance Man\u00a0\u00bb qui le suit ne sont sans doute pas la meilleure mani\u00e8re d&rsquo;y parvenir, flattant avec talent les convaincus sans pour autant faire un pas vers les plus sceptiques. Si on ne peut nier par exemple la beaut\u00e9 nostalgique de \u00ab\u00a0Facta Non Verba\u00a0\u00bb et les qualit\u00e9s progressives de \u00ab\u00a0Still Invictus\u00a0\u00bb, il est difficile de trouver sur <em>Sphere<\/em> des prises de distance nettes par rapport \u00e0 ses pr\u00e9d\u00e9cesseurs : les sentiers sont battus et rebattus, bien qu&rsquo;avec une certaine classe, il faut l&rsquo;avouer. Le final \u00ab\u00a0Bubonic Groove\u00a0\u00bb regroupe tout ce qui fait le charme surann\u00e9 de cette version du jazz fusion : le groove de la section rythmique, la rondeur de la production, la recherche de sons retro-futuristes, les m\u00e9lodies d\u00e9li\u00e9es et a\u00e9riennes \u00e0 la guitare \u00e9lectrique. Toute cette bonne volont\u00e9 fait plaisir \u00e0 entendre m\u00eame si le r\u00e9sultat confirme que le genre a v\u00e9cu, malgr\u00e9 cet \u00e9pilogue r\u00e9ellement honorable.<\/p>","protected":false},"excerpt":{"rendered":"<p>La fusion jazz \u00ab\u00a0spatiale\u00a0\u00bb &#8211; il faut bien trouver un nom \u00e0 une branche peu&#8230;<\/p>\n","protected":false},"author":14,"featured_media":7584,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[43,33,38],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/7583"}],"collection":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/comments?post=7583"}],"version-history":[{"count":0,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/7583\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media\/7584"}],"wp:attachment":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media?parent=7583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/categories?post=7583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/tags?post=7583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}