{"id":7531,"date":"2016-09-28T00:00:00","date_gmt":"2016-09-27T22:00:00","guid":{"rendered":"http:\/\/chromatique.net\/index.php\/2020\/04\/01\/7531"},"modified":"2016-09-28T00:00:00","modified_gmt":"2016-09-27T22:00:00","slug":"7531","status":"publish","type":"post","link":"https:\/\/www.chromatique.net\/index.php\/2016\/09\/28\/7531\/","title":{"rendered":"Jeremy Flower &#8211; The Real Me"},"content":{"rendered":"\n<p>Si vous suivez les conseils avis\u00e9s que vous distillent ces pages, alors vous avez d\u00e9j\u00e0 eu affaire \u00e0 Jeremy Flower. Invit\u00e9 par le duo am\u00e9ricain Rabbit Rabbit Radio, le multi-instrumentiste y allait de sa partie de guitare sur le titre d&rsquo;ouverture de l&rsquo;excellent <a href=\"http:\/\/chromatique.net\/chroniques\/item\/15387-rabbit-rabbit-radio-vol-3-year-of-the-wooden-horse\"><em>Year of the Wooden Horse<\/em><\/a>. Sur son album <em>The Real Me<\/em> (aucun hommage \u00e0 The Who en vue, <em>a priori<\/em>), il rend la pareille \u00e0 Carla Kihlstedt et Matthias Bossi, respectivement au violon \/ chant et \u00e0 la batterie. <br \/><br \/> Et on peut dire qu&rsquo;en termes d&rsquo;arrangements et de m\u00e9lange d&rsquo;instruments, il s&rsquo;y conna\u00eet. On le d\u00e9couvre imm\u00e9diatement avec le singulier \u00ab\u00a0Take\u00a0\u00bb, chanson pop o\u00f9 les parties orchestrales, explosives et sophistiqu\u00e9es, font mouche, quand quelques dissonances viennent surligner l&rsquo;\u00e9tranget\u00e9 de la composition. Une efficacit\u00e9 qu&rsquo;on retrouve sur le bref et tr\u00e8s \u00e9nergique \u00ab\u00a0Along The Banks\u00a0\u00bb. \u00ab\u00a0The Real Me\u00a0\u00bb, lente marche fun\u00e8bre travers\u00e9e de rares rayons de soleil ou le superbe \u00ab\u00a0The Loneliest Number\u00a0\u00bb t\u00e9moignent de la m\u00eame adresse pour m\u00ealer pop, musique de chambre et \u00e9lectronique discr\u00e8te. La belle Carla, doubl\u00e9e parfois par l&rsquo;\u00e9conome Jeremy, pose sa voix charmeuse sur des chansons dont l&rsquo;ambiance g\u00e9n\u00e9rale est plut\u00f4t sombre, ou du moins qui ne se pr\u00eatent pas aux d\u00e9bordements de joie, comme ce \u00ab\u00a0Blow Up\u00a0\u00bb folk nonchalant qui d\u00e9rive lentement vers un rock symphonique ou \u00ab\u00a0Stay With Me\u00a0\u00bb, touchante bande originale douce-am\u00e8re d&rsquo;un film intimiste. Les titres parlent d&rsquo;ailleurs souvent d&rsquo;eux-m\u00eames : \u00ab\u00a0As October Becomes\u00a0\u00bb, \u00ab\u00a0No Expectation of Sucess\u00a0\u00bb, \u00ab\u00a0False Comfort\u00a0\u00bb\u2026 Quelques moments plus <em>heavy<\/em> comme \u00ab\u00a0My Dove\u00a0\u00bb ou \u00ab\u00a0This Paradise\u00a0\u00bb secouent ce panier de m\u00e9lancolie tout en rajoutant un peu de drame \u00e0 la partition, s&rsquo;il en fallait encore. <br \/><br \/> Avec une grande ma\u00eetrise des atmosph\u00e8res, Jeremy Flower d\u00e9veloppe en quatorze titres et soixante-dix minutes une musique tr\u00e8s visuelle \u00e0 califourchon entre le rock ind\u00e9pendant et la pop, utilisant avec parcimonie des sonorit\u00e9s \u00e9lectroniques tout en tirant le meilleur parti de nombreux instruments acoustiques. Une science de l&rsquo;arrangement qui n&rsquo;est pas \u00e9trang\u00e8re \u00e0 la fascinante et triste beaut\u00e9 de <em>The Real Me<\/em>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Si vous suivez les conseils avis\u00e9s que vous distillent ces pages, alors vous avez d\u00e9j\u00e0&#8230;<\/p>\n","protected":false},"author":14,"featured_media":7532,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[25,60,120,23,24],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/7531"}],"collection":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/comments?post=7531"}],"version-history":[{"count":0,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/7531\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media\/7532"}],"wp:attachment":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media?parent=7531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/categories?post=7531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/tags?post=7531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}