{"id":73181,"date":"2022-04-04T10:39:54","date_gmt":"2022-04-04T08:39:54","guid":{"rendered":"https:\/\/www.chromatique.net\/?p=73181"},"modified":"2022-04-25T14:27:21","modified_gmt":"2022-04-25T12:27:21","slug":"frank-zappa-the-mothers-1971","status":"publish","type":"post","link":"https:\/\/www.chromatique.net\/index.php\/2022\/04\/04\/frank-zappa-the-mothers-1971\/","title":{"rendered":"Frank Zappa &#8211; The Mothers 1971"},"content":{"rendered":"\n<p><span><b>Dans la lign\u00e9e de <\/b><em style=\"font-weight: bold\">The Mothers 1970<\/em><b>, la Zappa Family Trust livre sa fourn\u00e9e annuelle avec ce coffret qui couvre une ann\u00e9e entre chaos et euphorie pour Frank Zappa. Apr\u00e8s<\/b><em style=\"font-weight: bold\"> <\/em><b>les<\/b><em style=\"font-weight: bold\"> <\/em><b>excellents <\/b><em style=\"font-weight: bold\">Zappa in New York Deluxe<\/em><b> ou<\/b><em style=\"font-weight: bold\"> The Roxy Performances<\/em><b>, voici donc 8 cds <\/b><\/span><strong><strong>riches de<\/strong><\/strong><strong><strong> 100 titres pour 6 shows complets. En compl\u00e9ment sortent \u00e9galement deux triples vinyles des shows au Fillmore East et au Rainbow Theater.<\/strong><\/strong><\/p>\n\n\n\n<p>C\u2019est en mai 1971 que notre moustachu pr\u00e9f\u00e9r\u00e9 part en tourn\u00e9e avec sa formation \u00e0 travers l\u2019Am\u00e9rique du Nord puis l\u2019Europe sans discontinuer. Surnomm\u00e9e \u201cThe Vaudeville Band\u201d, celle-ci comprend le duo \u201cFlo &amp; Eddie\u201d (Mark Volman &amp; Howard Kaylan, anciens chanteurs des Turtles), Aynsley Dunbar (batterie), Jim Pons (basse), Ian Underwood (sax\/claviers) et Bob Harris (claviers) qui sera remplac\u00e9 par le v\u00e9t\u00e9ran Don Preston.<\/p>\n\n\n\n<p>La joyeuse troupe, suite aux mouvements internes, finit par trouver un ton satirique et d\u00e9livre un discours anti-<em>establishment<\/em> fid\u00e8le \u00e0 Zappa. Le nouveau programme m\u00eale com\u00e9die bavarde et instrumentation solide, sortes de sketchs musicaux entour\u00e9s des pi\u00e8ces musicales classiques, le tout saupoudr\u00e9 d&rsquo;une bonne couche de bouffonnerie.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Fillmore East, New York, 5 et 6 Juin<\/strong><\/p>\n\n\n\n<p>Les 6 premiers disques sont d\u00e9di\u00e9s aux 4 shows de la r\u00e9sidence au Fillmore East de New York, devant une salle pleine \u00e0 craquer. Il faut dire que leur public, de plus en plus large et jeune, raffole de ces <em>happenings<\/em> dr\u00f4les et d\u00e9sinvoltes dont le bouche \u00e0 oreille porte le go\u00fbt du scandale.<\/p>\n\n\n\n<p>D\u2019embl\u00e9e, le <em>remastering<\/em> du son d\u00e9passe le <em>Fillmore East \u2013 June 71<\/em> ce qui classe d\u2019office cette box dans les indispensables.<\/p>\n\n\n\n<p>Les morceaux s&rsquo;encha\u00eenent m\u00e9caniquement d\u00e8s le d\u00e9part tonitruant de \u00abPeaches En Regalia\u00bb pour atteindre rapidement le sommet, l\u2019oratorio \u00abBilly the mountain\u00bb. Celui-ci ne fait jamais moins de 30 minutes qui sont n\u00e9cessaires \u00e0 la parodie rock-op\u00e9ra pour d\u00e9verser sa critique de la soci\u00e9t\u00e9 avec brio, sans conteste l\u2019apog\u00e9e de cette formation. Pr\u00e9texte aux plus excentriques improvisations, \u00abKing Kong\u00bb, parfois remplac\u00e9 par un \u00abChunga&rsquo;s revenge\u00bb est tout aussi efficace.<\/p>\n\n\n\n<figure class=\"wp-block-embed alignleft is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"&quot;Scumbag&quot; - Zappa, Lennon, Ono - Fillmore East 1971\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/T5SGC7hRjIo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><figcaption><em><strong>Ono, Lennon et Zappa tapent le boeuf<\/strong><\/em><\/figcaption><\/figure>\n\n\n\n<p>Enfin, comment ne pas \u00e9voquer ce rappel du 6 juin o\u00f9 John Lennon et Yoko Ono se sont invit\u00e9s spontan\u00e9ment sur sc\u00e8ne pour un b\u0153uf impr\u00e9vu. D\u00e9marr\u00e9 par un blues traditionnel \u00abWell\u00bb trop sage et ponctu\u00e9 par les ululations de Ono, celui-ci devient exaltant une fois nos amoureux pr\u00eat\u00e9s au jeu de la fameuse conduite au doigt du compositeur.<\/p>\n\n\n\n<p>Ravis par ce <em>one-off<\/em>, les deux protagonistes d\u00e9cident de sortir chacun de leur c\u00f4t\u00e9 cette r\u00e9union. Cependant, Lennon sortira d\u00e8s l\u2019ann\u00e9e suivante un mix d\u00e9natur\u00e9 et cisaill\u00e9, dont Zappa aura disparu des cr\u00e9dits; cela le forcera \u00e0 attendre le retour de ses bandes en 1992, pour en restituer la r\u00e9alit\u00e9 sur son <em>Playground Psychotics<\/em>.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Concert hybride, Pennsylvanie, 1 et 3 juin<\/strong><\/p>\n\n\n\n<p>Apr\u00e8s ce chapitre, le \u201cVaultmeister\u201d Joe Travers propose un concert hybride bas\u00e9 sur les pr\u00e9c\u00e9dentes dates \u00e0 Scranton et Harrisburg. Cette soir\u00e9e, avec une playlist d\u00e9j\u00e0 entendue 4 fois, reste tr\u00e8s dispensable. La ferveur du public, moins discr\u00e8te, les piquantes reprises d\u00e9su\u00e8tes ou encore les solos enflamm\u00e9s sur \u00abBilly The Mountain\u00bb permettent toutefois l&rsquo;\u00e9mergence d&rsquo;un certain charme.<\/p>\n\n\n\n<p>On estime que ces 80 minutes auraient pu \u00eatre mieux utilis\u00e9es, par exemple par d\u2019autres morceaux de choix absents ici, que ce soit du show du 7 ao\u00fbt \u00e0 l\u2019UCLA (dont est extrait <em>Just Another Band from L.A<\/em>, publi\u00e9 en 1972) \u2026 ou encore, celui du 4 d\u00e9cembre au Casino de Montreux qui fera l\u2019objet d\u2019un culte notamment gr\u00e2ce au <em>bootleg<\/em> <em>Swiss Cheese\/Fire<\/em>.<\/p>\n\n\n\n<figure class=\"wp-block-embed alignright is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Zappa And The Mothers &quot;200 Motels&quot; - Mystery Roach \/ Magic Fingers (Bizu Mix)\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/qAqaSXrykdc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><figcaption><em><strong>La formation 1971 dans le film 200 Motels<\/strong><\/em><\/figcaption><\/figure>\n\n\n\n<p>En effet, ce show rentrera dans la l\u00e9gende \u00e0 cause d&rsquo;un incident survenu \u00e0 sa fin, lorsque les 3000 spectateurs durent quitter prestement un casino en feu <a href=\"https:\/\/www.youtube.com\/watch?v=HD3SBLkjq1I&amp;t=2s\">\u00e0 cause du lancement d\u2019une fus\u00e9e \u00e9clairante<\/a>. Le groupe s\u2019en sortira sain et sauf, mais devra faire une croix sur son mat\u00e9riel sono et lumi\u00e8re. Toute cette histoire sera relat\u00e9e dans le morceau \u00abSmoke on the water\u00bb de Deep Purple pr\u00e9sents ce soir-l\u00e0.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Rainbow Theater, London, 10 d\u00e9cembre<\/strong><\/p>\n\n\n\n<p>Le show londonien qui conclut ce tour est l\u2019unique t\u00e9moignage de leur p\u00e9riple europ\u00e9en. Eux-m\u00eame n\u2019auraient pas imagin\u00e9 ce genre de m\u00e9saventure dans leur film <em>200 motels<\/em> tout juste sorti, qui raconte ironiquement l&rsquo;absurdit\u00e9 et la lassitude des d\u00e9placements sans fin lors des tourn\u00e9es (o\u00f9 quand la r\u00e9alit\u00e9 rejoint la fiction). C\u00f4t\u00e9 technique, on assiste l\u00e0 aussi \u00e0 un sans faute pour ce concert remix\u00e9 par le grand Eddie Kramer qui y apporte clart\u00e9, \u00e9quilibre et pr\u00e9sence.<\/p>\n\n\n\n<p>Les Mothers ont donc d\u00fb r\u00e9cup\u00e9rer du mat\u00e9riel au plus vite, comme en t\u00e9moigne cette balance en d\u00e9but du show vite d\u00e9dramatis\u00e9e par un Zappa toujours caustique. Et une fois le point fait, la magie revient vite. On sent que le groupe a gagn\u00e9 en coh\u00e9sion et en virtuosit\u00e9, avec un l\u00e9ger abandon de la com\u00e9die. Parmi les points forts, une nouvelle suite intitul\u00e9e \u00abDivan\u00bb, incompl\u00e8te ici, o\u00f9 ce long couloir instrumental \u00abPound for a brown\u00bb \/ \u00abSleeping in a jar\u00bb, repr\u00e9sente incontestablement le moment fort de la soir\u00e9e. Certaines exp\u00e9rimentations font penser \u00e0 la folie des premiers Mothers (\u00abSuper grease\u00bb), et la musique se fait volontiers de plus en plus jazz rock, quand bien m\u00eame les amateurs de rock <em>uptempo<\/em> appr\u00e9cieront la dyade \u00abWonderful Wino\u00bb \/ \u00abSharleena\u00bb.<\/p>\n\n\n\n<p>H\u00e9las! Apr\u00e8s un \u00abKing Kong\u00bb jouissif de 20 minutes, le rappel en clin d&rsquo;\u0153il \u00abI wanna hold your hand\u00bb va de nouveau \u00eatre g\u00e2ch\u00e9 par <a href=\"https:\/\/www.youtube.com\/watch?v=tOt2F5czB_A\">un spectateur qui pousse Frank du haut de la sc\u00e8ne<\/a>, qui, dans la stupeur g\u00e9n\u00e9rale, chutera de plusieurs m\u00e8tres. Ce choc glacial de derni\u00e8re minute viendra contraster la joie d\u00e9bordante qui r\u00e9gnait jusqu&rsquo;alors. Cet ultime \u00e9v\u00e9nement sonnera ainsi le glas de la tourn\u00e9e et de la formation, autant qu\u2019il impactera le reste de la vie de Frank Zappa en termes de sant\u00e9 mais aussi de direction artistique. Laiss\u00e9 pour seul et suite \u00e0 une r\u00e9\u00e9ducation intensive de 6 mois, il se r\u00e9inventera courant 1972 en chef d\u2019orchestre jazz fusion avec les captivants <em>Waka\/Jawaka et The Grand Wazoo<\/em>.<\/p>\n\n\n\n<p>Outre le caract\u00e8re historique, c\u2019est donc avant tout la qualit\u00e9 sonore exceptionnelle qui fait l\u2019int\u00e9r\u00eat de ce coffret, nonobstant la quantit\u00e9 de musique (certes encore loin des mastodontes de King Crimson) qui totalise 10 heures&nbsp;d\u2019archives. Une s\u00e9lection plus courte et vari\u00e9e aurait certainement \u00e9t\u00e9 aussi efficace, surtout si l\u2019on consid\u00e8re les quelques moments phares absents ici.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-3 is-cropped\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"300\" height=\"300\" data-id=\"74202\"  src=\"https:\/\/www.chromatique.net\/wp-content\/uploads\/2022\/03\/wkg_6-300x300-1.jpeg\" alt=\"\" class=\"wp-image-74202\" srcset=\"https:\/\/www.chromatique.net\/wp-content\/uploads\/2022\/03\/wkg_6-300x300-1.jpeg 300w, https:\/\/www.chromatique.net\/wp-content\/uploads\/2022\/03\/wkg_6-300x300-1-150x150.jpeg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption>Smoke on the water (Montreux, d\u00e9cembre 1971)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"335\" height=\"400\" data-id=\"73363\"  src=\"https:\/\/www.chromatique.net\/wp-content\/uploads\/2022\/03\/The_pit71-12-10.jpg\" alt=\"\" class=\"wp-image-73363\" srcset=\"https:\/\/www.chromatique.net\/wp-content\/uploads\/2022\/03\/The_pit71-12-10.jpg 335w, https:\/\/www.chromatique.net\/wp-content\/uploads\/2022\/03\/The_pit71-12-10-251x300.jpg 251w\" sizes=\"(max-width: 335px) 100vw, 335px\" \/><figcaption>When the curtain drops (Londres, d\u00e9cembre 1971)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1219\" height=\"1500\" data-id=\"74473\"  src=\"https:\/\/www.chromatique.net\/wp-content\/uploads\/2022\/03\/DQttBX3VQAA8dH6.jpeg\" alt=\"\" class=\"wp-image-74473\" srcset=\"https:\/\/www.chromatique.net\/wp-content\/uploads\/2022\/03\/DQttBX3VQAA8dH6.jpeg 1219w, https:\/\/www.chromatique.net\/wp-content\/uploads\/2022\/03\/DQttBX3VQAA8dH6-244x300.jpeg 244w, https:\/\/www.chromatique.net\/wp-content\/uploads\/2022\/03\/DQttBX3VQAA8dH6-832x1024.jpeg 832w, https:\/\/www.chromatique.net\/wp-content\/uploads\/2022\/03\/DQttBX3VQAA8dH6-768x945.jpeg 768w, https:\/\/www.chromatique.net\/wp-content\/uploads\/2022\/03\/DQttBX3VQAA8dH6-1024x1260.jpeg 1024w\" sizes=\"(max-width: 1219px) 100vw, 1219px\" \/><figcaption>\u00ab\u00a0One of my legs is shorter than the other\u00a0\u00bb (en studio, 1972)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"400\" height=\"269\" data-id=\"74470\"  src=\"https:\/\/www.chromatique.net\/wp-content\/uploads\/2022\/03\/Yoko_Ono_Zappa_and_John_Lennon.jpg\" alt=\"\" class=\"wp-image-74470\" srcset=\"https:\/\/www.chromatique.net\/wp-content\/uploads\/2022\/03\/Yoko_Ono_Zappa_and_John_Lennon.jpg 400w, https:\/\/www.chromatique.net\/wp-content\/uploads\/2022\/03\/Yoko_Ono_Zappa_and_John_Lennon-300x202.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><figcaption>A small eternity with Yoko Ono (New York, juin 1971)<\/figcaption><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Dans la lign\u00e9e de The Mothers 1970, la Zappa Family Trust livre sa fourn\u00e9e annuelle&#8230;<\/p>\n","protected":false},"author":12,"featured_media":73361,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2,35],"tags":[53,231,46,180,24],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/73181"}],"collection":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/comments?post=73181"}],"version-history":[{"count":107,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/73181\/revisions"}],"predecessor-version":[{"id":75720,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/73181\/revisions\/75720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media\/73361"}],"wp:attachment":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media?parent=73181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/categories?post=73181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/tags?post=73181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}