{"id":7227,"date":"2015-08-26T00:00:00","date_gmt":"2015-08-25T22:00:00","guid":{"rendered":"http:\/\/chromatique.net\/index.php\/2020\/04\/01\/7227"},"modified":"2015-08-26T00:00:00","modified_gmt":"2015-08-25T22:00:00","slug":"7227","status":"publish","type":"post","link":"https:\/\/www.chromatique.net\/index.php\/2015\/08\/26\/7227\/","title":{"rendered":"Exovex &#8211; Radio Silence"},"content":{"rendered":"\n<p>Josh Freese, Richard Barbieri, Gavin Harisson, Keith Carlock : en voil\u00e0 du beau monde ! Les invit\u00e9s de Dale Simmons sur son projet Exovex au premier album sobrement intitul\u00e9 \u00ab\u00a0 Radio Silence\u00a0 \u00bb ne font pas p\u00e2le figure pour une formation de musique progressive.<br \/><br \/> La couleur est donn\u00e9e d\u00e8s le premier morceau : \u00ab\u00a0 Radio Silence\u00a0 \u00bb est fait pour les amateurs de Porcupine Tree. Nappes sobres de Barbieri, basse lente et pos\u00e9e, accords bross\u00e9s \u00e0 l&rsquo;acoustique : la recette du Porcupine Tree pop est l\u00e0. Si effectivement la comparaison semble omnipr\u00e9sente, Dale Simmons aux guitares, basses et chant, a quand m\u00eame quelques tours dans son sac, bien personnels. On note notamment quelques solos de guitare bien sentis, et un sens de la composition un peu plus direct que son comparse britannique. L&rsquo;album s&rsquo;\u00e9tale sur six pistes, pr\u00e9sentant la m\u00eame face d&rsquo;une pi\u00e8ce : un rock se voulant atmosph\u00e9rique et \u00e9nergique par alternance. \u00ab\u00a0Seeker&rsquo;s Praye\u00a0\u00bb pr\u00e9sente extr\u00eamement bien le concept du long de ses neuf minutes alternant riffs metal, et passages acoustiques plus envol\u00e9s. <br \/><br \/> S&rsquo;il ne s&rsquo;agit pas de l&rsquo;album du si\u00e8cle, et si les inspirations sautent aux yeux, il faut tout de m\u00eame accepter l&rsquo;id\u00e9e que \u00ab\u00a0Radio Silence\u00a0\u00bb est un excellent ersatz de ce qui se fait de mieux dans le genre, Porcupine Tree et Pink Floyd en t\u00eate. Dale Simmons nous procure donc un album d&rsquo;excellente qualit\u00e9, sans grande originalit\u00e9 certes, mais d&rsquo;une facture incriticable qui saura ravir les fans du genre.<\/p>","protected":false},"excerpt":{"rendered":"<p>Josh Freese, Richard Barbieri, Gavin Harisson, Keith Carlock : en voil\u00e0 du beau monde !&#8230;<\/p>\n","protected":false},"author":26,"featured_media":7228,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[71,38,24],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/7227"}],"collection":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/comments?post=7227"}],"version-history":[{"count":0,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/7227\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media\/7228"}],"wp:attachment":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media?parent=7227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/categories?post=7227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/tags?post=7227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}