{"id":6973,"date":"2015-12-06T00:00:00","date_gmt":"2015-12-05T23:00:00","guid":{"rendered":"http:\/\/chromatique.net\/index.php\/2020\/04\/01\/6973"},"modified":"2015-12-06T00:00:00","modified_gmt":"2015-12-05T22:00:00","slug":"6973","status":"publish","type":"post","link":"https:\/\/www.chromatique.net\/index.php\/2015\/12\/06\/6973\/","title":{"rendered":"Alco Frisbass &#8211; Alco Frisbass"},"content":{"rendered":"\n<p>De chaque espace de cr\u00e9ativit\u00e9 musicale s\u2019extrait une s\u00e8ve qui coule jusqu\u2019\u00e0 nourrir le fond des esgourdes de ceux qui veulent bien les ouvrir. Dans cette n\u00e9buleuse artistique o\u00f9 se c\u00f4toient d\u00e9tenteurs subjectifs du pouvoir m\u00e9diatique et inconnus confirm\u00e9s pourtant pr\u00e9sents sur le catalogue des sorties, se cachaient derri\u00e8re le post\u00e9rieur d\u2019un certain Alco Frisbass, deux Fran\u00e7ais multit\u00e2ches aux capacit\u00e9s insoup\u00e7onn\u00e9es. Avec ce premier album \u00e9ponyme, le projet a de quoi s\u00e9rieusement int\u00e9resser les fondus de rock progressif, curieux et aventureux.<br \/><br \/> Compos\u00e9 de six longs titres instrumentaux, <em>Alco Frisbass<\/em> est un panach\u00e9 h\u00e9t\u00e9roclite de rock progressif avant-gardiste par bien des aspects. Celui qui retient la premi\u00e8re attention est l\u2019effet claviers et basse  plac\u00e9s en avant. Les sons se multiplient tr\u00e8s vite, tout comme les lignes m\u00e9lodiques tr\u00e8s actives et attirantes. Ensuite l\u2019aspect harmonique et m\u00e9lodique, celui qui peut pr\u00e9tendre avoir une influence sur l\u2019auditeur, est consid\u00e9rable car chaque th\u00e8me semble actionner une partie du cerveau qui dit : \u00ab\u00a0oh que c\u2019est bon \u00e7a !\u00a0\u00bb.<br \/> Beaucoup de passages sont des r\u00e9f\u00e9rences \u00e0 des groupes cultes qu\u2019il est inutile de citer. Alco Frisbass fonctionne parfaitement en son nom propre. Une sorte de t\u00e9moignage captivant et d\u00e9licieusement concoct\u00e9 par deux passionn\u00e9s. Parall\u00e8lement au fait qu\u2019ind\u00e9niablement ce premier album soit une v\u00e9ritable r\u00e9ussite, il y a le questionnement de ce qui est v\u00e9ritablement jou\u00e9 et de ce qui est programm\u00e9 ou arrang\u00e9 en dehors de la batterie. M\u00eame si les deux musiciens sont pourvus de capacit\u00e9s certaines, car les morceaux ne sont r\u00e9ellement pas simples, ce petit d\u00e9tail interpelle.<br \/> Au-del\u00e0 de cela, le choix des longues dur\u00e9es, composante importante, permet de justifier le style d\u00e9velopp\u00e9. Chaque piste part d\u2019une riche id\u00e9e m\u00e9lodique et s\u2019allonge d\u00e9mesur\u00e9ment. Alco Frisbass ne fait pas dans la surench\u00e8re de riffs, mais va pousser loin la construction de th\u00e8mes et le jeu autour de ceux-l\u00e0. La d\u00e9marche emprunte au jazz mais aussi \u00e0 la musique classique, vraiment bluffant.<br \/><br \/> V\u00e9ritable voyage au c\u0153ur d\u2019un univers contrast\u00e9 et changeant, ce disque est le r\u00e9sultat d\u2019un \u00e9norme travail de composition et t\u00e9moigne d\u2019un amour inconditionnel pour un style musical qui perdure depuis plus de quarante-cinq ans sous diverses formes. On passe d\u2019ambiances m\u00e9lancoliques \u00e0 souriantes et inversement en un rien de temps, un v\u00e9ritable plaisir \u00e0 conseiller fortement.<\/p>","protected":false},"excerpt":{"rendered":"<p>De chaque espace de cr\u00e9ativit\u00e9 musicale s\u2019extrait une s\u00e8ve qui coule jusqu\u2019\u00e0 nourrir le fond&#8230;<\/p>\n","protected":false},"author":4,"featured_media":6974,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[53,38,24],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/6973"}],"collection":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/comments?post=6973"}],"version-history":[{"count":0,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/6973\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media\/6974"}],"wp:attachment":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media?parent=6973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/categories?post=6973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/tags?post=6973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}