{"id":3935,"date":"2007-12-10T00:00:00","date_gmt":"2007-12-09T23:00:00","guid":{"rendered":"http:\/\/chromatique.net\/index.php\/2020\/04\/01\/3935"},"modified":"2007-12-10T00:00:00","modified_gmt":"2007-12-09T22:00:00","slug":"3935","status":"publish","type":"post","link":"https:\/\/www.chromatique.net\/index.php\/2007\/12\/10\/3935\/","title":{"rendered":"Jean-Pascal Boffo &#8211; La bo\u00eete \u00e0 musique"},"content":{"rendered":"<p>Jean-Pascal Boffo, excellent guitariste de son \u00e9tat, est connu des amateurs de rock progressif au sens large du terme puisqu\u2019\u00e0 c\u00f4t\u00e9 d\u2019une carri\u00e8re en solo prolifique (huit albums tous aussi r\u00e9ussis les uns que les autres), il a \u00e9galement jou\u00e9 avec Christian D\u00e9camps sur les tr\u00e8s r\u00e9ussis <i>Nu<\/i> et <i>Vesoul<\/i> en 1994 et 1995. Il m\u00e8ne \u00e9galement de front le projet Alifair avec Herv\u00e9 Rouyer (ex-Ange) \u00e0 la batterie et la charmante Aurore Reichert au chant. Le qualifier de Steve Hackett fran\u00e7ais serait r\u00e9ducteur tant les compositions de Boffo peuvent nous mener en contr\u00e9es diff\u00e9rentes \u00e0 chaque fois. Certes, le ma\u00eetre \u00e8s guitares de la Gen\u00e8se a fortement influenc\u00e9 Jean-Pascal Boffo. Mais il faudrait alors \u00e9galement citer Anthony Philips (premier guitariste de Genesis), Mike Oldfield ou encore Andy Latimer (Camel).  <\/p>\n<p>  Le nouvel album du ma\u00eetre \u00e0 r\u00eaver est enti\u00e8rement acoustique. Le seul instrument utilis\u00e9 est la guitare acoustique. Ainsi, naturellement et par la force des choses, l\u2019auditeur est amen\u00e9 \u00e0 penser beaucoup aux travaux intimistes de Steve Hackett. D\u2019ailleurs, \u00e0 certains moments, ce dernier est presque cit\u00e9 par Jean-Pascal Boffo. M\u00eames arp\u00e8ges cristallins, semblables constructions harmoniques et pareille dext\u00e9rit\u00e9 dans le doigt\u00e9. Il est vrai que ce dernier album de Jean-Pascal Boffo, bien que de qualit\u00e9, n\u2019est peut-\u00eatre pas le travail le plus original qu\u2019il ait produit. Mais comment l\u2019\u00eatre avec une guitare classique pour seul outil ? Si un n\u00e9ophyte souhaitait entrer dans le monde merveilleux du grand Boffo, il faudrait peut-\u00eatre qu\u2019il acquiert en premier lieu les chefs-d\u2019\u0153uvre que sont <i>Nomades<\/i> (1993) ou <i>Infini<\/i> (2004). Sinon, se prendre une claque magistrale en \u00e9coutant le travail proprement hallucinant que fait Jean-Pascal Boffo sur le pantagru\u00e9lique enregistrement live du p\u00e8re D\u00e9camps, <i>Vesoul<\/i>, d\u00e9j\u00e0 cit\u00e9. Ses soli sur le mythique \u00ab&nbsp;Capitaine C\u0153ur de Miel&nbsp;\u00bb donnent le frisson. In\u00e9galable. <br \/> Les douze compositions qui constituent cette bo\u00eete \u00e0 musique de toute beaut\u00e9 sont de vraies perles harmoniques, \u00e0 savourer pr\u00e8s d\u2019une chemin\u00e9e mais surtout, \u00e0 l\u2019aide d\u2019un bon syst\u00e8me hi-fi. Ainsi, la finesse du jeu et le toucher si ma\u00eetris\u00e9 du ma\u00eetre d\u2019\u0153uvre sont manifestes. <\/p>\n<p>  L\u2019album sied magnifiquement \u00e0 cette douce m\u00e9lancolie de No\u00ebl sans en poss\u00e9der le revers mi\u00e8vre et gentillet. Cette <i>Bo\u00eete \u00e0 musique<\/i> est le disque essentiel de cet hiver. A \u00e9couter pendant que, dehors, le froid et la neige vous redonneront envie de remettre le disque sur la platine. Encore et encore. Le cadeau de No\u00ebl id\u00e9al pour gens raffin\u00e9s. De bien meilleur go\u00fbt qu\u2019un vulgaire <i>Best of<\/i> de plus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jean-Pascal Boffo, excellent guitariste de son \u00e9tat, est connu des amateurs de rock progressif au&#8230;<\/p>\n","protected":false},"author":5,"featured_media":3936,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/3935"}],"collection":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/comments?post=3935"}],"version-history":[{"count":0,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/3935\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media\/3936"}],"wp:attachment":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media?parent=3935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/categories?post=3935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/tags?post=3935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}