{"id":20874,"date":"2009-10-19T00:00:00","date_gmt":"2009-10-18T22:00:00","guid":{"rendered":"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/de9cfa552966abfe609e5d46cba8e802_XL.jpg"},"modified":"2009-10-19T00:00:00","modified_gmt":"2009-10-18T22:00:00","slug":"20874","status":"publish","type":"post","link":"https:\/\/www.chromatique.net\/index.php\/2009\/10\/19\/20874\/","title":{"rendered":"Shadow Gallery &#8211; Shadow Gallery"},"content":{"rendered":"<table width=\"100%\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">   <tr>      <td class=\"tablecentre Style1\">        <h1>ENTRETIEN : SHADOW GALLERY<\/h1>       <table width=\"100%\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">         <tr>            <td width=\"50%\" valign=\"top\"><img loading=\"lazy\" alt=\"\" src=\"\/images\/contenu\/articles\/old\/int_sg09_main.jpg\" width=\"220\" height=\"150\" border=\"1\"><\/td>           <td width=\"3%\" valign=\"top\">&nbsp;<\/td>           <td width=\"47%\" valign=\"top\" class=\"maintext\">              \n<p>   <b>Origine :<\/b> Etats-Unis<\/b><br \/> <b>Style :<\/b> metal progressif<\/b> <br \/> <b>Form\u00e9 en :<\/b> 1983<\/b><br \/> <b>Composition :<\/b>  <br \/>             Brian Ashland  \u2013 chant <br \/> Brendt Allman \u2013 guitare, ch\u0153urs <br \/> Gary Wehrkamp \u2013 guitare, ch\u0153urs, claviers<br \/> Carl Cadden-James \u2013 basse &#038; ch\u0153urs, fl\u00fbte<br \/> Joe Nevolo \u2013 batterie<br \/> <b>Album \u00e0 para\u00eetre :<\/b> <i>Digital Ghosts<\/i> (2009)     <\/span>          <\/p>           <\/td>         <\/tr>       <\/table>       <p align=\"justify\" class=\"dateconcert\"><b>La nouvelle \u00e9tait tomb\u00e9e comme une claque en novembre 2008 lorsque nous apprenions la disparition de Mike Baker, l&#8217;embl\u00e9matique chanteur de Shadow Gallery, des suites d&rsquo;une crise cardiaque. Orphelin de son vocaliste, le groupe s&rsquo;est terr\u00e9 dans un mutisme pour n&rsquo;en ressortir que plus fort avec la sortie d&rsquo;un nouvel album et ce premier entretien exclusif mondial qu&rsquo;a donn\u00e9 Gary Wehrkamp pour Progressia, jouant le jeu \u00e0 fond \u2013 parfois non sans \u00e9motion \u2013, n&rsquo;\u00e9ludant aucune question et r\u00e9pondant avec toute la passion, la sympathie et la sinc\u00e9rit\u00e9 qui le caract\u00e9rise. Les fant\u00f4mes du pass\u00e9 ressurgissent pour cette nouvelle \u00e8re digitale.<br \/><br \/>  Progressia : Il y a bient\u00f4t cinq ans, Shadow Gallery rejoignait InsideOut Music. Quel bilan tires-tu de la p\u00e9riode qui a suivi votre signature ?<\/b><br \/> <b>Gary Wehrkamp<\/b> : Je me suis investi sur des projets en parall\u00e8le comme Expedition Delta avec le guitariste Srdjan Brankovic, Dream Tone, Amaran\u2019s Plight avec lesquels j\u2019ai mis en boite <i>Voice in the Light<\/i> ainsi que Terra Incognito. J\u2019aime \u00eatre occup\u00e9 entre nos enregistrements de Shadow Gallery, bien que parfois il s&rsquo;av\u00e8re que nous sommes finalement tous d\u00e9bord\u00e9s avec tous ses projets qui viennent se greffer sur nos agendas. La plupart du temps, ce qui reste le plus difficile, c&rsquo;est de red\u00e9marrer le moteur. Au del\u00e0 de \u00e7a, J&rsquo;ai \u00e9galement ouvert mon studio d&rsquo;enregistrement et son lancement implique d\u2019autres processus. Une fois que nous avions commenc\u00e9 \u00e0 maquetter, la machine \u00e9tait lanc\u00e9e.<br \/><br \/>  <img loading=\"lazy\" alt=\"\" src=\"\/images\/contenu\/articles\/old\/int_sg09_2.jpg\" width=\"175\" height=\"175\" align=\"right\" border=\"1\"><b>Rentrons dans le vif du sujet : nous avons tous \u00e9t\u00e9 extr\u00eamement choqu\u00e9s par le d\u00e9c\u00e8s de Mike. Quelle a \u00e9t\u00e9 la premi\u00e8re pens\u00e9e venue \u00e0 l&rsquo;esprit ? Abandonner ? Faire un break ou pensiez-vous que c&rsquo;est dans l&rsquo;adversit\u00e9 que vous vous \u00eates le plus soud\u00e9s ?<\/b><br \/> Rien de tout cela. Il \u00e9tait n\u00e9anmoins \u00e9vident que Shadow Gallery devait \u00eatre un temps mis entre parenth\u00e8ses, ne serait-ce que par respect pour les proches de Mike. Car avant d&rsquo;\u00eatre des musiciens, nous sommes li\u00e9s par une tr\u00e8s forte amiti\u00e9, et c&rsquo;est plus dur de perdre un ami que de devoir retrouver un chanteur. Ce drame est survenu alors que nous avions d\u00e9j\u00e0 des titres de pr\u00eat : Brendt et moi-m\u00eame avions travaill\u00e9 sur beaucoup de mat\u00e9riel, Carl s&rsquo;\u00e9tait occup\u00e9 des textes et lignes de chant. Mike ne participait jamais vraiment \u00e0 la composition mais lorsqu&rsquo;il a \u00e9cout\u00e9 les d\u00e9mos que nous avions rassembl\u00e9es, \u00e7a l&rsquo;a motiv\u00e9 en un claquement de doigts. Je ne l&rsquo;avais jamais vu comme \u00e7a ! Je p\u00e8se mes mots, il n&rsquo;avait qu&rsquo;une envie : entrer en studio et en d\u00e9coudre. C&rsquo;est tellement frustrant. Il devait enregistrer chez lui des lignes de chant basiques afin de d\u00e9fricher un peu le terrain, alors qu&rsquo;il avait son d\u00e9m\u00e9nagement sur le feu qui prenait du temps. Il est d\u00e9c\u00e9d\u00e9 la veille de mettre les voiles&#8230; Dans tous les cas, il n&rsquo;a jamais \u00e9t\u00e9 question de mettre un terme \u00e0 Shadow Gallery.<br \/><br \/>  <b>La communaut\u00e9 progressive internationale a r\u00e9agi de mani\u00e8re unanime \u00e0 l&rsquo;annonce de son d\u00e9c\u00e8s. Si les t\u00e9moignages sont venus du monde entier, l&rsquo;un des hommages les plus touchants \u00e0 sans doute \u00e9t\u00e9 celui d&rsquo;Arjen Lucassen\u2026<\/b><br \/> Arjen a effectivement \u00e9t\u00e9 assez marqu\u00e9 et ce fut l&rsquo;un des premiers \u00e0 \u00eatre au courant de la disparition de Mike et ce, \u00e0 la demande de Denise, sa compagne. Je voulais imprimer tous ces messages de soutien pour les fun\u00e9railles de Mike et les remettre \u00e0 Denise ainsi qu&rsquo;\u00e0 sa famille, mais je n&rsquo;ai malheureusement pu m&rsquo;en occuper car c&rsquo;est un travail de longue haleine. Il y avait d&rsquo;une part, pr\u00e8s de huit cent messages et d&rsquo;autre part, imprimer toutes ces marques d&rsquo;affection sur une feuille rend la lecture p\u00e9nible, car les caract\u00e8res sont minuscules. Sachez toutefois qu&rsquo;ils ont \u00e9t\u00e9 tr\u00e8s appr\u00e9ci\u00e9s et qu&rsquo;ils nous sont all\u00e9s droit au c\u0153ur et \u00e0 ceux des proches de Mike. J&rsquo;ai pris le temps de lire tous les t\u00e9moignages envoy\u00e9s sur Myspace, toutes ces marques de soutien et de sympathie ainsi que toutes les condol\u00e9ances adress\u00e9es sur notre forum. Je vais \u00eatre honn\u00eate avec toi : jusqu&rsquo;\u00e0 son d\u00e9c\u00e8s, je ne me suis jamais vraiment souci\u00e9 de l&rsquo;impact de Shadow Gallery. J&rsquo;ai toujours pens\u00e9, sans pour autant les d\u00e9nigrer, loin de l\u00e0, que nous n&rsquo;avions qu&rsquo;une poign\u00e9e de fans. Or les r\u00e9actions \u00e0 la disparition de Mike m&rsquo;ont fait prendre conscience du nombre important de gens qui nous supportent, et je profite de la perche que vous nous tendez pour remercier toutes ces personnes du monde entier qui nous ont t\u00e9moign\u00e9 leur support dans ces moments difficiles. Je sais que Facebook inclut le principe des <i>fan pages<\/i> et apprendre que des passionn\u00e9s comme vous pr\u00eachent la bonne parole, c&rsquo;est extr\u00eamement gratifiant, car cela prouve que nous ne faisons pas cette musique pour rien. C&rsquo;est dans de telles situations comme celle-ci que nous voyons vraiment l&rsquo;importance des fans. <br \/><br \/>  <img loading=\"lazy\" alt=\"\" src=\"\/images\/contenu\/articles\/old\/int_sg09_3.jpg\" width=\"321\" height=\"175\" align=\"left\" border=\"1\"><b>Cet \u00e9v\u00e8nement majeur vous a-t-il fait modifier votre ligne de conduite sur le plan artistique ? Je t&rsquo;avais pos\u00e9 une question semblable \u00e0 l&rsquo;\u00e9poque de <i>Room V<\/i> et tu m&rsquo;avais r\u00e9pondu ne pas avoir inclus de nouveaux \u00e9l\u00e9ments musicaux telles que des musiques typ\u00e9es orientales ou des percussions, de peur de sortir du concept de Shadow Gallery. Vous \u00eates-vous dits cette fois-ci <i>no limits<\/i> ou \u00eates-vous rest\u00e9s fid\u00e8les \u00e0 votre devise ?<\/b><br \/> Il y a effectivement quelques nouveaut\u00e9s comme des percussions. Je n&rsquo;\u00e9coute pas beaucoup de musique en temps normal pour \u00eatre franc, encore moins depuis que j&rsquo;ai mon studio d&rsquo;enregistrement dans lequel je passe mon temps \u00e0 produire et \u00e0 enregistrer des groupes. Ma contribution a \u00e9t\u00e9 de rendre le disque encore plus progressif. Brendt, quant \u00e0 lui, a inclus beaucoup d&rsquo;\u00e9l\u00e9ments et de th\u00e8mes emprunt\u00e9s au jazz-fusion puisqu&rsquo;il en est un fervent amateur. Cela a eu pour effet d\u2019amener une certaine fraicheur \u00e0 notre musique. Le r\u00e9sultat final risque donc d&rsquo;en surprendre plus d\u2019un ! <br \/><br \/>  <b>Lors de notre pr\u00e9c\u00e9dent entretien, tu avais mentionn\u00e9 que le concept d\u00e9marr\u00e9 sur <i>Tyranny<\/i> et poursuivi sur <i>Room V<\/i> continuerait et qu\u2019il s\u2019intitulerait <i>Two Shadows<\/i>\u2026 Est-ce toujours le cas aujourd\u2019hui ?<\/b><br \/> Effectivement, c&rsquo;est bien ce que je t&rsquo;avais dit \u00e0 l&rsquo;\u00e9poque, mais il n\u2019a jamais \u00e9t\u00e9 question que ce soit pour ce nouveau disque. La disparition de Mike n\u2019est pas la raison premi\u00e8re de ce changement. Tout s\u2019est fait naturellement, en toute fluidit\u00e9 comme c&rsquo;\u00e9tait le cas entre <i>Tyranny<\/i> et <i>Legacy<\/i>. Apres <i>Room V<\/i>, nous \u00e9tions quelque peu cram\u00e9s. Nous aurions pu poursuivre le concept mais nos choix ont d\u00e9vi\u00e9 vers  des chansons ind\u00e9pendantes. Au moment o\u00f9 je te parle, il n\u2019y a donc pas de plans pour un double album, sauf revirement de situation, et pas de disque bonus.<br \/><br \/>  <b>Parlons du successeur de Mike. Une rumeur circulait sur la pr\u00e9sence de D.C. Cooper (Silent Force, Amaran\u2019s Plight) sur un titre et sugg\u00e9rait \u00e9ventuellement un poste \u00e0 temps complet&#8230;<\/b><br \/> Pour \u00eatre totalement honn\u00eate, cette possibilit\u00e9 de le voir sur le long terme \u00e0 ce poste ne nous a m\u00eame pas effleur\u00e9 l\u2019esprit. Je l&rsquo;adore, autant l\u2019homme que le musicien avec j\u2019ai eu la chance de bosser sur des projets parall\u00e8les, mais nous ne l\u2019avons pas choisi pour succ\u00e9der \u00e0 Mike ni pour chanter sur un tite.<br \/><br \/>  <b>Avez-vous d\u00e8s lors re\u00e7u beaucoup de candidatures ? Avez-vous d\u00e9j\u00e0 port\u00e9 votre choix sur un \u00e9ventuel candidat ? Si oui, peux-tu nous donner son nom de l\u2019heureux \u00e9lu ? <\/b><br \/> La musique \u00e9tait d\u00e9j\u00e0 compos\u00e9e au moment o\u00f9 nous sommes tomb\u00e9s d\u2019accord. Nous avons trouv\u00e9 quelqu\u2019un qui cadre parfaitement avec ce que nous recherchions : Brian Ashland. Il poss\u00e8de son style et n\u2019essaie en aucun cas de copier Mike. De toute fa\u00e7on, la plus parfaite des copies ne sera jamais l\u2019\u00e9gal de l\u2019original et sera d\u2019office jet\u00e9e \u00e0 la poubelle. Concernant le nombre de candidats, nous n\u2019en avons pas eu des masses\u2026<br \/><br \/>  <img loading=\"lazy\" alt=\"\" src=\"\/images\/contenu\/articles\/old\/int_sg09_4.jpg\" width=\"296\" height=\"175\" align=\"right\" border=\"1\"><b>C\u2019est-\u00e0-dire ?<\/b><br \/> (<i>visiblement g\u00ean\u00e9<\/i>) Nous en avons auditionn\u00e9 moins d\u2019une dizaine\u2026 Moins de cinq en r\u00e9alit\u00e9 (<i>rires<\/i>). Ils ne se sont pas bouscul\u00e9s au portillon pour tenter leur chance. Cela \u00e9tant dit, nous n\u2019avions pas d\u2019objectifs en terme de nombre de candidats, car \u00eatre un groupe de notre relative envergure nous \u00e9vite d&rsquo;avoir de sacr\u00e9es migraines lors d\u2019\u00e9ventuelles auditions. J&rsquo;aime appartenir \u00e0 Shadow Gallery et je ne m&rsquo;imagine certainement pas \u00eatre dans Iron Maiden au moment de d\u00e9signer le rempla\u00e7ant de Bruce Dickinson ! (<i>rires<\/i>) <br \/><br \/>  <b>Nous avons d&rsquo;ailleurs pu d\u00e9couvrir les talents de Carl sur <i>Room V<\/i> \u00e9clater au grand jour. As-tu d\u00e9j\u00e0 pens\u00e9 qu&rsquo;il pouvait \u00eatre le chanteur idoine ?<\/b><br \/> C\u2019est vrai que Carl chante tr\u00e8s bien. Nous en avons parl\u00e9 entre nous, et de son propre aveu, c\u2019est bien la derni\u00e8re personne qui postulerait pour ce boulot. <br \/><br \/>  <b>Cela t&rsquo;a-t-il incit\u00e9 \u00e0 chanter davantage ?<\/b><br \/> Brendt, Carl et moi faisons tous les ch\u0153urs donc c\u2019est d\u00e9j\u00e0 pas mal. Mais \u00e0 l\u2019avenir, pourquoi pas ? <br \/><br \/>   <b>En plus de DC, d\u2019autres invit\u00e9s sont-ils pr\u00e9vus sur le disque ?<\/b><br \/> Oui, il y aura Srdjan Brankovic, l\u2019\u00e9minence grise d\u2019Expedition Delta et le clavi\u00e9riste fran\u00e7ais Vivien Lalu qui nous a sorti un solo absolument extraordinaire ! <br \/><br \/>  <img loading=\"lazy\" alt=\"\" src=\"\/images\/contenu\/articles\/old\/int_sg09_5.jpg\" width=\"263\" height=\"175\" align=\"left\" border=\"1\"><b>Es-tu \u00e0 nouveau unique producteur de l\u2019album ?<\/b><br \/> L\u2019album a \u00e9t\u00e9 enregistr\u00e9 en grande partie au New Horizon Studio que je poss\u00e8de. Carl et Brendt ont enregistr\u00e9 certaines de leurs parties chez eux. N\u00e9anmoins, on peut parler aujourd\u2019hui de co-production, car Brendt s\u2019est \u00e9norm\u00e9ment investi dans le processus. Il m\u2019a beaucoup aid\u00e9, notamment lorsqu&rsquo;il s\u2019agissait d\u2019enregistrer mes parties. J\u2019avais cette tendance \u00e0 vouloir tout superviser et rarement d\u00e9l\u00e9guer, mais Brendt est arriv\u00e9 avec son lot d\u2019id\u00e9es. Le r\u00e9sultat s\u2019en retrouve vraiment enrichi et conf\u00e8re ainsi une certaine fraicheur \u00e0 l\u2019ensemble.<br \/><br \/>  <b>Chris Ingles est-il de retour dans le groupe ?<\/b><br \/> La situation n\u2019a pas r\u00e9ellement \u00e9volu\u00e9 sur ce sujet. (<i>NdlR : la situation de Chris Ingles est quelque peu ambigu\u00eb depuis la sortie de <\/i>Room V<i>. Aucun communiqu\u00e9 officiel ne mentionne sp\u00e9cifiquement son d\u00e9part<\/i>)<br \/><br \/>  <b>Tu auras remarqu\u00e9 que je ne t\u2019ai pas pos\u00e9 la sempiternelle question : \u00ab&nbsp;<i>Qu\u2019en est-il d&rsquo;\u00e9ventuels projets de tourn\u00e9e ?<\/i>&nbsp;\u00bb ! (<i>rires<\/i>)<\/b><br \/> Et c\u2019est tr\u00e8s bien ! (<i>rires<\/i>) C\u2019est vrai que cette question revient inlassablement, mais que peut-on y faire ? Dans un sens, c\u2019est normal. D\u2019un autre cot\u00e9, je pense que les gens ont compris que ce serait difficile.<br \/><br \/>  <b>A toi de conclure cet entretien\u2026<\/b><br \/> Vous avez \u00e9t\u00e9 avec nous \u00e0 vos d\u00e9buts et nous \u00e9tions d\u00e9j\u00e0 ravis de figurer dans vos colonnes papier. Votre soutien est donc vraiment de premier ordre et un r\u00e9el honneur. Je profite de l\u2019occasion que tu me donnes pour remercier l&rsquo;\u00e9quipe de Progressia, ses lecteurs ainsi que toutes les personnes qui nous ont t\u00e9moign\u00e9 leur sympathie et leur soutien face \u00e0 l\u2019adversit\u00e9 et cette terrible \u00e9preuve qui a vu un de nos amis partir pr\u00e9matur\u00e9ment.  <\/p>       <p align=\"right\" class=\"dateconcert\"><strong>Propos recueillis par Dan Tordjman<\/strong><\/p>       <p align=\"center\" class=\"dateconcert\"><strong>site web : <\/strong><a href=\"http:\/\/www.shadowgallery.com\" target=\"_blank\" class=\"dateconcert\"><font color=\"#0000FF\"><strong>Shadow Gallery<\/strong><\/font><\/a><\/p>       <p align=\"center\" class=\"dateconcert\"><strong><a href=\"http:\/\/http:\/\/www.chromatique.net\/index.php?option=com_k2&#038;view=itemlist&#038;layout=category&#038;task=category&#038;id=2&#038;Itemid=4\"><font color=\"#CA0B4E\"><font color=\"#157175\">retour          au sommaire<\/font><\/font><\/a><\/strong><\/p>     <\/td>   <\/tr> <\/table>","protected":false},"excerpt":{"rendered":"<p>ENTRETIEN : SHADOW GALLERY &nbsp; Origine : Etats-Unis Style : metal progressif Form\u00e9 en :&#8230;<\/p>\n","protected":false},"author":9,"featured_media":20875,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/20874"}],"collection":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/comments?post=20874"}],"version-history":[{"count":0,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/20874\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media\/20875"}],"wp:attachment":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media?parent=20874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/categories?post=20874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/tags?post=20874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}