{"id":19069,"date":"2012-03-26T00:00:00","date_gmt":"2012-03-25T22:00:00","guid":{"rendered":"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-07.jpg"},"modified":"2012-03-26T00:00:00","modified_gmt":"2012-03-25T22:00:00","slug":"19069","status":"publish","type":"post","link":"https:\/\/www.chromatique.net\/index.php\/2012\/03\/26\/19069\/","title":{"rendered":"The Aristocrats &#8211; La classe en toute simplicit\u00e9"},"content":{"rendered":"\n<p><strong> Apr\u00e8s un premier album encens\u00e9 \u00e0 juste titre, le passage des Aristocrats \u00e0 Paris \u00e9tait attendu de pied ferme par bon nombre de fans. Chromatique revient sur cette soir\u00e9e o\u00f9 le trio infernal a \u00e9clabouss\u00e9 la Sc\u00e8ne Bastille de son talent.<\/strong><br \/><br \/> En ce mercredi soir, la Sc\u00e8ne Bastille est copieusement garnie et pr\u00eate \u00e0 passer un moment sous le signe de la virtuosit\u00e9, de l\u2019humour et de la d\u00e9contraction. Et comme il est question de d\u00e9contraction, c\u2019est \u00e0 une bonne connaissance de Feu-Progressia que revient la charge d\u2019ouvrir les hostilit\u00e9s, en la personne de Cyril Achard. Ce soir, le guitariste a jou\u00e9 la carte de la simplicit\u00e9, seul sur sc\u00e8ne, avec sa guitare classique. Le Fran\u00e7ais parvient \u00e0 tisser une ambiance chaude et ensoleill\u00e9e. Quoi de plus appropri\u00e9 en cette soir\u00e9e printani\u00e8re ? Les reprises de \u00ab\u00a0Sunny\u00a0\u00bb de Bobby Hebb &amp; \u00ab\u00a0Ain\u2019t No Sunshine\u00a0\u00bb de Bill Withers font mouche. Entre temps, le public, plut\u00f4t r\u00e9ceptif, eut droit \u00e0 une jolie version de \u00ab\u00a0Persepolia\u00a0\u00bbavant que Cyril ne termine son set sur une derni\u00e8re et d\u00e9licieuse reprise de \u00ab\u00a0Georgy Porgy\u00a0\u00bb de Toto. Un ap\u00e9ritif savoureux, l\u00e9ger, de saison en somme, id\u00e9al pour ouvrir l\u2019app\u00e9tit des nombreux musiciens pr\u00e9sents ce soir dans l\u2019auditoire.<br \/><br \/> C\u2019est un Marco Minnemann tout sourire, sac \u00e0 dos sur l\u2019\u00e9paule, qui arpente le premier l\u2019espace sc\u00e9nique, suivi par Guthrie Govan et Bryan Beller. Les trois lascars sont pr\u00eats et d\u00e9marrent leur set en larguant un \u00ab\u00a0Bad Asteroid\u00a0\u00bb, charg\u00e9 de planter le d\u00e9cor. Ce soir, le trio n\u2019est pas venu pour conter fleurette. Preuve suppl\u00e9mentaire avec un \u00ab\u00a0Sweaty Knockers\u00a0\u00bb de feu au cours duquel les plombs de Marco Minnemann sautent une premi\u00e8re fois, pour le plus grand plaisir des spectateurs. Apr\u00e8s avoir retrouv\u00e9 ses esprits, le batteur allemand pr\u00e9sente, dans un fran\u00e7ais parfait, le prochain titre \u00ab\u00a0Boing\u2026 I\u2019m In The Back\u00a0\u00bb. L\u2019esprit de connivence et de franche rigolade est bien pr\u00e9sent sur et face \u00e0 la sc\u00e8ne. Les trois comp\u00e8res sont en grande forme, avec un Bryan Beller, terriblement efficace \u00e0 la basse, dont les grimaces donneraient presque lieu \u00e0 un concours. Guthrie Govan quant \u00e0 lui est presque \u00e9c\u0153urant de facilit\u00e9 \u00e0 encha\u00eener les acrobaties sur son manche.<br \/><br \/> L\u2019ambiance survolt\u00e9e dispara\u00eet et laisse place \u00e0 une atmosph\u00e8re bien plus pos\u00e9e et feutr\u00e9e le temps de \u00ab\u00a0Flatlands\u00a0\u00bb. Cette savoureuse accalmie \u00e9tait en r\u00e9alit\u00e9 un message pour pr\u00e9parer le terrain \u00e0 la prochaine secousse du trio infernal : intitul\u00e9e \u00ab\u00a0Blues Fuckers\u00a0\u00bb, elle voit Marco Minnemann p\u00eater les plombs une seconde fois au cours d\u2019un solo de batterie absolument \u00e9pileptique. Disons-le, on n\u2019\u00e9tait pas loin de le perdre ! Pour rester dans la folie, \u00ab\u00a0See You Next Tuesday\u00a0\u00bb, issu de la plume de Bryan Beller, maintient le niveau sismique avant que l\u2019on entende la d\u00e9claration d\u2019amour de la soir\u00e9e sign\u00e9e Guthrie Govan, qui avoue son envie surprenante d\u2019acqu\u00e9rir \u2026 un perroquet ! Oui, l\u2019Anglais semble aimer ces oiseaux au point de leur d\u00e9dier un titre : \u00ab\u00a0I Want A Parrot\u00a0\u00bb. L\u2019histoire ne nous dit pas s\u2019il a finalement r\u00e9alis\u00e9 son caprice.<br \/><br \/> Enfin, le guitariste nous offre une part de ses fameux \u00ab\u00a0Erotic Cakes\u00a0\u00bb, suivie d\u2019une reprise fumante du \u00ab\u00a0Zomby Woof\u00a0\u00bb de Frank Zappa. En y r\u00e9fl\u00e9chissant, que serait un concert des Aristocrats sans un l\u00e9gitime clin d\u2019\u0153il au Grand Wazoo ? Difficile de le savoir, mais pour \u00eatre franc, c\u2019est le cadet des soucis du public de la Sc\u00e8ne Bastille. Avec des \u00e9toiles plein les yeux, les spectateurs quittent les lieux, non sans se voir ass\u00e9ner un dernier taquet nomm\u00e9 \u00ab\u00a0Waves\u00a0\u00bb, id\u00e9al pour cl\u00f4turer une soir\u00e9e riche en notes et rires. Au fait, si par hasard quelqu\u2019un retrouvait la camisole de force de Marco Minnemann, pri\u00e8re de contacter la r\u00e9daction qui transmettra.<\/p>\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-08.jpg\" alt=\"\" data-id=\"19071\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-08.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=19071\" class=\"wp-image-19071\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-04.jpg\" alt=\"\" data-id=\"19072\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-04.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=19072\" class=\"wp-image-19072\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-06.jpg\" alt=\"\" data-id=\"19073\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-06.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=19073\" class=\"wp-image-19073\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-05.jpg\" alt=\"\" data-id=\"19074\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-05.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=19074\" class=\"wp-image-19074\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-09.jpg\" alt=\"\" data-id=\"19075\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-09.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=19075\" class=\"wp-image-19075\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-02.jpg\" alt=\"\" data-id=\"19076\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-02.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=19076\" class=\"wp-image-19076\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-03.jpg\" alt=\"\" data-id=\"19077\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-03.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=19077\" class=\"wp-image-19077\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/__MACOSX\" alt=\"\" data-id=\"19078\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/__MACOSX\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=19078\" class=\"wp-image-19078\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-01.jpg\" alt=\"\" data-id=\"19079\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-01.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=19079\" class=\"wp-image-19079\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-07.jpg\" alt=\"\" data-id=\"19080\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/13667\/20120314-LaScene-TheAristocrats-07.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=19080\" class=\"wp-image-19080\"\/><\/figure><\/li><\/figure><\/ul>","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":19070,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/19069"}],"collection":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/comments?post=19069"}],"version-history":[{"count":0,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/19069\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media\/19070"}],"wp:attachment":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media?parent=19069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/categories?post=19069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/tags?post=19069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}