{"id":18708,"date":"2011-06-27T00:00:00","date_gmt":"2011-06-26T22:00:00","guid":{"rendered":"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-05.jpg"},"modified":"2011-06-27T00:00:00","modified_gmt":"2011-06-26T22:00:00","slug":"18708","status":"publish","type":"post","link":"https:\/\/www.chromatique.net\/index.php\/2011\/06\/27\/18708\/","title":{"rendered":"Metallurgicales 2011 &#8211; La vie en Rouge"},"content":{"rendered":"\n<p><strong>Les <em>Metallurgicales<\/em>, festival mont\u00e9 il y a trois ans par le regrett\u00e9 Patrick Roy a ouvert ses portes \u00e0 Denain (Nord) le onze juin pour une journ\u00e9e sous le signe de la double p\u00e9dale. La r\u00e9cente disparition de son p\u00e8re fondateur en fit par l\u00e0 m\u00eame un magnifique hommage o\u00f9 le d\u00e9sormais fameux costume rouge fut c\u00e9l\u00e9br\u00e9 par des cohortes de t-shirts noirs. R\u00e9trospective sur cette journ\u00e9e pleine \u00ab\u00a0de Gibson et de Marshall\u00a0\u00bb.<\/strong><br \/><br \/> Les portes du festival ouvrent \u00e0 partir de midi laissant les \u00ab\u00a0l\u00e8ve-t\u00f4t\u00a0\u00bb se presser autour du complexe sportif de Denain o\u00f9 la journ\u00e9e s\u2019annonce d\u00e9j\u00e0 chaude. Les quelques stands (nourriture et march\u00e9) leur permettent d\u2019attendre l\u2019ouverture officielle des hostilit\u00e9s \u00e0 quinze heures. En patientant du c\u00f4t\u00e9 du \u00ab\u00a0march\u00e9\u00a0\u00bb, le stand <em>Engine Pickups<\/em> pr\u00e9sente une petite d\u00e9monstration de mat\u00e9riel (des micros pour guitare) en pr\u00e9sence d\u2019Aymeric Silvert et de Beno\u00eet Pol. Autre attraction int\u00e9ressante, Stefan Forte, leader d\u2019<em>Adagio<\/em> leur succ\u00e8de et vient jouer quelques morceaux sous la forme d\u2019un master-class pour Lag quelques instants avant le d\u00e9but des concerts.<br \/><br \/> Quinze heures : ouverture officielle des hostilit\u00e9s et pr\u00e9sentation du rituel de la journ\u00e9e. Avant chaque concert, le public a droit \u00e0 un extrait d\u2019intervention de Patrick Roy sur le metal. Les morceaux choisis sont divers et vari\u00e9s, mais qu\u2019il s\u2019agisse de prises de parole \u00e0 l\u2019assembl\u00e9e nationale ou \u00e0 la t\u00e9l\u00e9vision, elles auront toujours pour but de rappeler l\u2019ouverture d\u2019esprit du personnage vis-\u00e0-vis des musiques extr\u00eames. Ce gimmick accompagn\u00e9 de \u00ab\u00a0Struggle Within\u00a0\u00bb de <em>Metallica<\/em> revient comme une piq\u00fbre de rappel sur l\u2019origine du festival, sur ses objectifs et sur la perte r\u00e9cente du rh\u00e9teur favori des metalleux.<br \/><br \/> Le d\u00e9but des concerts est annonc\u00e9 et le premier groupe \u00e0 fouler les planches de la sc\u00e8ne ext\u00e9rieure est Sueurs Froides, les enfants terribles du pays. La musique est pour le moins enjou\u00e9e et les diff\u00e9rents membres n\u2019h\u00e9sitent pas \u00e0 faire le show et ce, m\u00eame en ouverture de festival en proposant un hard survolt\u00e9 et d\u00e9jant\u00e9. Entre deux morceaux, la maire de Denain profite que le groupe reprenne son souffle pour nous adresser un discours pr\u00e9sentant le festival et rappelant son p\u00e8re fondateur. Au cours de son set, Sueurs Froide rend deux hommages \u00e0 Patrick Roy : Le premier, sous la forme d\u2019une \u00ab\u00a0minute de bruit\u00a0\u00bb, mettra la foule particuli\u00e8rement en \u00e9bullition ; le second, sous celle d\u2019un morceau hommage, la mettra en \u00e9moi. L\u2019un dans l\u2019autre, bien que leur musique ne r\u00e9volutionne probablement pas le monde des auditeurs, cette prestation permet l\u2019ouverture du festival en bonne et due forme.<br \/><br \/> Leur performance termin\u00e9e, c\u2019est au tour de Dagoba de prendre possession de la sc\u00e8ne principale. Les Marseillais ne sont pas en reste depuis la sortie de leur dernier album <em>Poseidon<\/em> et roulent litt\u00e9ralement sur le public, l\u2019\u00e9crasant de leur musique intense et sur-vitamin\u00e9e par le jeu de Franky Costanza \u00e0 la batterie. Le set nous confirme d\u00e9finitivement que la troupe m\u00e9rite son succ\u00e8s international. Elle propose en effet une performance professionnelle pr\u00e9sentant un metal industriel \u00e0 la fois puissant et m\u00e9lodique. Avec un jeu de sc\u00e8ne bien pr\u00e9sent sans \u00eatre excessif et une foule connaisseuse chantant en ch\u0153ur et r\u00e9pondant aux appels de Shawter, le groupe avait tout pour faire un sans faute. Malheureusement, le son un peu brouillon (le \u00ab\u00a0sur-vitaminage\u00a0\u00bb de la batterie se transformant vite en sur-mixage) rend le concert un peu difficile \u00e0 suivre et ternit le tableau.<br \/><br \/> Changement d\u2019ambiance \u00e0 dix-sept heures avec Hacride qui, \u00e0 la diff\u00e9rence d\u2019un Dagoba rapide et impulsif, nous livre une musique lente et lourde, charg\u00e9e d\u2019atmosph\u00e8res inqui\u00e9tantes. On regrettera leur pr\u00e9sence sur sc\u00e8ne \u00e0 ce moment-l\u00e0 de la journ\u00e9e. Le groupe aurait en effet pu b\u00e9n\u00e9ficier de la p\u00e9nombre ou au moins d\u2019un espace moins lumineux pour mieux plonger l\u2019audience dans leur univers. La performance reste tout de m\u00eame admirable et l\u2019on peut s\u2019\u00e9tonner en toute honn\u00eatet\u00e9 que les Fran\u00e7ais ne partagent pas la sc\u00e8ne int\u00e9rieure tant leur production est de qualit\u00e9. Fait amusant : cette musique puissante et assur\u00e9e cr\u00e9e un fort contraste avec le groupe sur sc\u00e8ne tant les musiciens donnent l\u2019impression d\u2019\u00eatre timides. Qu\u2019\u00e0 cela ne tienne, le set permet de tenir en haleine les spectateurs de sa premi\u00e8re \u00e0 sa derni\u00e8re note !<br \/><br \/> Que les amateurs de progressif se r\u00e9jouissent ensuite car voici venu le temps du set du Devin Townsend Project. Le Canadien annonce imm\u00e9diatement la couleur en montant sur sc\u00e8ne la mine r\u00e9jouie, confirmant ses dires lors de notre <a href=\"index.php?option=com_k2&amp;view=item&amp;id=12790&amp;Itemid=6\">derni\u00e8re interview<\/a>. Une prestation qui se place sous les auspices de la bonne humeur, de la blague et de l\u2019intensit\u00e9 famili\u00e8res du personnage. Son mur de son nous frappe de plein fouet d\u00e8s les premiers accords, m\u00eame un peu trop. La batterie encore une fois trop pr\u00e9sente ruine en partie la prestation. Pour autant, les spectateurs des premiers rangs ne se sentent pourtant pas l\u00e9s\u00e9s tellement Devin joue pour eux, allant tr\u00e8s souvent se placer sur les avanc\u00e9es devant la fosse afin de faire profiter son public (et les photographes) d\u2019une vue spectaculaire sur ses mimiques inimitables. La set-list pioche dans  la quasi-totalit\u00e9 de la discographie du \u00ab\u00a0project\u00a0\u00bb et du \u00ab\u00a0band\u00a0\u00bb. Cerise sur le g\u00e2teau, le public se voit servi en guise d\u2019amuse-bouche une avant-premi\u00e8re de <a href=\"index.php?option=com_k2&amp;view=item&amp;id=12805&amp;Itemid=12\"><em>Deconstruction<\/em><\/a>, troisi\u00e8me  album du projet. <br \/><br \/> Manigance encha\u00eene sur la sc\u00e8ne ext\u00e9rieure. Ce groupe de metal-symphonique fran\u00e7ais produira une prestation peu marquante \u00e0 laquelle seuls les fans de la premi\u00e8re heure assisteront avec assiduit\u00e9. Pour le reste, elle encouragera le public \u00e0 retourner devant la sc\u00e8ne principale en attente de la formation suivante.<br \/><br \/> Therion prend ensuite place \u00e0 l\u2019int\u00e9rieur du gymnase. Premier constat : la mise en sc\u00e8ne grand guignolesque en met plein les mirettes aux premiers rangs de spectateurs. Le son, pour la premi\u00e8re et unique fois de la journ\u00e9e, est absolument parfait (ce qui est assez exceptionnel en festival pour \u00eatre not\u00e9). Tout sera tr\u00e8s bien \u00e9quilibr\u00e9 et donnera au groupe une prestance et une spatialisation exemplaires. Apr\u00e8s quelques morceaux, il serait faire preuve de mauvaise foi de r\u00e9futer que le jeu de sc\u00e8ne millim\u00e9tr\u00e9, la mise en place et la bonne humeur du groupe gomment en grande partie ses ridicules accoutrements. D\u2019ailleurs, la foule ne s\u2019y trompe pas et entre d\u00e8s l\u2019introduction dans le jeu des musiciens, en r\u00e9pondant \u00e0 chaque appel. Les riffs ultra-efficaces et les soli abondants contrastent avec le chant lyrique des quatre choristes et les quelques apart\u00e9s \u00e0 la flute traversi\u00e8re servis par Thomas Vikstr\u00f6m. Le r\u00e9pertoire couvert par les Su\u00e9dois remontera m\u00eame jusqu\u2019\u00e0 leurs plus vieux albums, satisfaisant ainsi les membres les plus exigeants du public. On peut n\u00e9anmoins regretter la pr\u00e9sence de samples d\u00e9mod\u00e9s qui jettent un nouveau voile de ridicule sur certains morceaux aux arrangements pourtant diablement efficaces.<br \/><br \/> Dernier groupe \u00e0 fouler les planches de la sc\u00e8ne ext\u00e9rieure, les fran\u00e7ais d\u2019Aqme dont on n\u2019entend plus parler depuis des ann\u00e9es. Ce groupe de metal ayant pourtant d\u00e9fray\u00e9 la chronique au d\u00e9but des ann\u00e9es 2000 s\u2019est compl\u00e8tement fait oublier du public ces derniers temps. Loin d\u2019\u00eatre la catastrophe \u00e0 laquelle on est en droit de s\u2019attendre, la prestation reste int\u00e9ressante mais n\u00e9anmoins pas particuli\u00e8rement inoubliable. Le public pr\u00e9f\u00e8re donc se presser vers l\u2019int\u00e9rieur o\u00f9 les pr\u00e9paratifs pour Stratovarius sont d\u00e9j\u00e0 bien entam\u00e9s.<br \/><br \/> L\u2019ultime concert de la soir\u00e9e est pr\u00e9c\u00e9d\u00e9 d\u2019un dernier hommage \u00e0 Patrick Roy sous la forme d\u2019un diaporama accompagn\u00e9 d\u2019extraits de discours du d\u00e9funt d\u00e9put\u00e9. En guise de pr\u00e9liminaires, la maire de Denain nous adresse elle aussi un dernier salut avant de laisser la place \u00e0 Stradivarius (sic) qui mettra encore de longues minutes avant de monter sur sc\u00e8ne. Apr\u00e8s une introduction pour le moins martiale, la troupe finlandaise arrive sur sc\u00e8ne et l\u00e0 \u2026 c\u2019est le drame. Un son brouillon, un chanteur accusant l\u2019\u00e2ge et ne pouvant pas tenir ses notes, voir les zappant compl\u00e8tement, des sons de clavier r\u00e9tro. Stratovarius est arriv\u00e9 au fil des ann\u00e9es \u00e0 la parfaite ma\u00eetrise d\u2019un metal sans saveur, sans originalit\u00e9 et sans grand int\u00e9r\u00eat. Une partie des d\u00e9fauts s\u2019\u00e9clipsent progressivement avec l\u2019avanc\u00e9e du set (notamment Timo Kotipelto au chant qui finira par \u00eatre chaud apr\u00e8s une demi-heure de concert). Notons tout de m\u00eame le jeu de sc\u00e8ne tr\u00e8s pr\u00e9sent et l\u2019\u00e9nergie d\u00e9ploy\u00e9e par le groupe qui enflammera la foule. Cependant, m\u00eame si le set aurait pu ravir les fans de la premi\u00e8re heure (leur rappelant probablement leurs jeunes ann\u00e9es), pour les autres le festival est d\u00e9j\u00e0 termin\u00e9 et le reste de la foule s\u2019achemine progressivement vers la sortie vidant le complexe sportif de Denain. <br \/><br \/> En d\u00e9pit de quelques probl\u00e8mes de son n\u2019entamant que peu la qualit\u00e9 des concerts, les Metallurgicales de Denain ont prouv\u00e9 qu\u2019elles n\u2019avaient rien \u00e0 envier aux autres festivals concernant leur programmation. Malgr\u00e9 la disparition de son instigateur, nul doute que le festival se poursuivra sans inqui\u00e9tude les prochaines ann\u00e9es et attirera probablement de plus en plus de spectateurs. Cette journ\u00e9e fut un magnifique hommage \u00e0 Patrick Roy. Gageons que peu de spectateurs oublieront le c\u00e9l\u00e8bre costume rouge de l\u2019assembl\u00e9e nationale.<\/p>\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-11.jpg\" alt=\"\" data-id=\"18710\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-11.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=18710\" class=\"wp-image-18710\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-14.jpg\" alt=\"\" data-id=\"18711\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-14.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=18711\" class=\"wp-image-18711\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-09.jpg\" alt=\"\" data-id=\"18712\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-09.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=18712\" class=\"wp-image-18712\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-15.jpg\" alt=\"\" data-id=\"18713\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-15.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=18713\" class=\"wp-image-18713\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-08.jpg\" alt=\"\" data-id=\"18714\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-08.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=18714\" class=\"wp-image-18714\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-01.jpg\" alt=\"\" data-id=\"18715\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-01.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=18715\" class=\"wp-image-18715\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-12.jpg\" alt=\"\" data-id=\"18716\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-12.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=18716\" class=\"wp-image-18716\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-06.jpg\" alt=\"\" data-id=\"18717\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-06.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=18717\" class=\"wp-image-18717\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-13.jpg\" alt=\"\" data-id=\"18718\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-13.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=18718\" class=\"wp-image-18718\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-03.jpg\" alt=\"\" data-id=\"18719\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-03.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=18719\" class=\"wp-image-18719\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-07.jpg\" alt=\"\" data-id=\"18720\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-07.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=18720\" class=\"wp-image-18720\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-16.jpg\" alt=\"\" data-id=\"18721\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-16.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=18721\" class=\"wp-image-18721\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-04.jpg\" alt=\"\" data-id=\"18722\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-04.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=18722\" class=\"wp-image-18722\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-10.jpg\" alt=\"\" data-id=\"18723\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-10.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=18723\" class=\"wp-image-18723\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-02.jpg\" alt=\"\" data-id=\"18724\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-02.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=18724\" class=\"wp-image-18724\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-05.jpg\" alt=\"\" data-id=\"18725\" data-full-url=\"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/12821\/110611_Selection_Metallurgicales-05.jpg\" data-link=\"http:\/\/www.chromatique.net\/?attachment_id=18725\" class=\"wp-image-18725\"\/><\/figure><\/li><\/figure><\/ul>","protected":false},"excerpt":{"rendered":"","protected":false},"author":26,"featured_media":18709,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/18708"}],"collection":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/comments?post=18708"}],"version-history":[{"count":0,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/18708\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media\/18709"}],"wp:attachment":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media?parent=18708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/categories?post=18708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/tags?post=18708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}