{"id":18102,"date":"2009-06-08T00:00:00","date_gmt":"2009-06-07T22:00:00","guid":{"rendered":"http:\/\/chromatique.net\/wp-content\/uploads\/2020\/04\/769e5a84ad9c9a4f6246ca350c3f28f3_XL.jpg"},"modified":"2009-06-08T00:00:00","modified_gmt":"2009-06-07T22:00:00","slug":"18102","status":"publish","type":"post","link":"https:\/\/www.chromatique.net\/index.php\/2009\/06\/08\/18102\/","title":{"rendered":"Ange &#8211; Ange"},"content":{"rendered":"<table width=\"100%\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tr>\n<td class=\"tablecentre\">\n<h1>CONCERT : ANGE<\/h1>\n<table width=\"100%\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tr>\n<td width=\"50%\" valign=\"top\"><img loading=\"lazy\" alt=\"\" src=\"\/images\/contenu\/articles\/old\/live_ange09_main.jpg\" width=\"220\" height=\"150\" border=\"1\"><\/td>\n<td width=\"3%\" valign=\"top\">&nbsp;<\/td>\n<td width=\"47%\" valign=\"top\" class=\"maintext\">   <b>Lieu :<\/b> G\u00e9rardmer, Espace LAC<br \/>  <b>Date :<\/b> 09 mai 2009<br \/>  <b>Photos :<\/b> St\u00e9phanie Guitton et Jean-Philippe Haas  <\/p>\n<p>             <\/span>            <\/td>\n<\/tr>\n<\/table>\n<p align=\"justify\" class=\"dateconcert\">  <i>Setlist : <\/i>Tous les boomerangs du monde \u2013 La gare de Troyes \u2013 Exode \u2013 Dieu est un escroc \u2013 La b\u00eate \u2013 Aur\u00e9lia \u2013 Harmonie \u2013 Coup\u00e9e en deux \u2013 Je travaille sans filet \u2013 Ode \u00e0 Emile \u2013 Souffleurs de vers (synopsis) \u2013 Souffleurs de vers (le film) \u2013 Saga \u2013 Catiline \u2013 Juste une ligne bleue \u2013 Quasimodo (<i>Merci \u00e0 \u00ab\u00a0Fils de lumi\u00e8re\u00a0\u00bb du forum d\u2019Un Pied Dans La Marge pour la liste des titres<\/i>).<\/p>\n<p>  <b>Durant deux jours, sous l\u2019impulsion d\u2019un fan-club hyperactif et passionn\u00e9 (http:\/\/www.updlm.com\/) la Convention Ange 2009 a r\u00e9uni les fans qui ont eu le courage de faire le d\u00e9placement jusqu\u2019aux rives du lac de G\u00e9rardmer, dans les Vosges. Et ils sont venus des quatre coins de France, les plaques d\u2019immatriculation des v\u00e9hicules \u00e9taient l\u00e0 pour  l\u2019attester ! Point d\u2019orgue de la tourn\u00e9e \u00ab&nbsp;Souffleurs de Vers&nbsp;\u00bb, le concert confirme le potentiel sc\u00e9nique de l\u2019album, avant la prochaine grande \u00e9tape : le quaranti\u00e8me anniversaire du groupe.<\/b><\/p>\n<p>  Plut\u00f4t que de chercher des groupes similaires pour assurer la premi\u00e8re partie, Christian D\u00e9camps, a souhait\u00e9 faire plaisir \u00e0 des amis musiciens qu\u2019il vient d\u2019ailleurs pr\u00e9senter lui-m\u00eame sur sc\u00e8ne. Ainsi, ce sont aux hard-rockeurs de Messaline \u00e0 qui il revient d\u2019ouvrir les hostilit\u00e9s. Et malgr\u00e9 beaucoup de bonne volont\u00e9, cette entr\u00e9e en mati\u00e8re est laborieuse : le son est ignoble, beaucoup trop fort et en fera fuir plus d\u2019un. Le heavy metal plut\u00f4t basique de Messaline ne fait pas l&rsquo;unanimit\u00e9, c\u2019est le moins qu\u2019on puisse dire. Malgr\u00e9 tout, l\u2019assistance reste indulgente et patiente. L\u2019ambiance change du tout au tout lorsque le trio Alifair, compos\u00e9 de Jean-Pascal Boffo, d\u2019Herv\u00e9 Rouyer et de la charmante Aurore Reichert (au chant et&#8230;\u00e0 la basse !) vient nous conter ses histoires joliment \u00e9crites dans une ambiance intime et sur une musique \u00e0 cheval entre la pop et le jazz. Un groupe attachant \u00e0 d\u00e9couvrir, \u00e0 l\u2019aide par exemple du petit dernier, <i>Fort Int\u00e9rieur<\/i> (http:\/\/www.myspace.com\/alifairband). <\/p>\n<p>  <img loading=\"lazy\" alt=\"\" src=\"\/images\/contenu\/articles\/old\/live_ange09_2.jpg\" width=\"220\" height=\"150\" align=\"right\" border=\"1\">Apr\u00e8s cette mise en bouche pour le moins contrast\u00e9e, le concert d\u00e9marre en trombe avec l\u2019ouverture de <i>Souffleurs de Vers<\/i>, le tr\u00e8s accrocheur \u00ab&nbsp;Tous les boomerangs du monde&nbsp;\u00bb, suivi par le non moins vigoureux \u00ab&nbsp;La gare de Troyes&nbsp;\u00bb, un titre devenu contre toute attente un classique des concerts d\u2019Ange. D\u2019embl\u00e9e, le public est assailli par l\u2019incroyable \u00e9nergie que d\u00e9gagent D\u00e9camps et sa bande. On sent que le spectacle a \u00e9t\u00e9 rod\u00e9 en tourn\u00e9e. Celui-ci acoquine le neuf avec l\u2019ancien et alterne sans temps morts les moments h\u00e9ro\u00efques et les passages recueillis, l\u2019\u00e9nergie brute et les tensions th\u00e9\u00e2tralis\u00e9es. <\/p>\n<p>  <img loading=\"lazy\" alt=\"\" src=\"\/images\/contenu\/articles\/old\/live_ange09_4.jpg\" width=\"220\" height=\"150\" align=\"left\" border=\"1\">Les projecteurs s\u2019attardent certes sur le P\u00e8re mais aussi sur le Fils et ses Enfants spirituels. Car si Christian D\u00e9camps tient \u00e9videmment le beau r\u00f4le, Caroline Crozat est devenue en quelques ann\u00e9es un \u00e9l\u00e9ment essentiel du spectacle et force le respect par son charisme. Qu\u2019il s\u2019agisse de l\u2019intime \u00ab&nbsp;Coup\u00e9e en deux&nbsp;\u00bb ou du tr\u00e8s conceptuel \u00ab&nbsp;Souffleurs de vers&nbsp;\u00bb, sa pr\u00e9sence apporte un contrepoids vital \u00e0 l\u2019omnipotence de Christian D\u00e9camps. Le duo se donne la r\u00e9plique, se  croise, se compl\u00e8te. Quant \u00e0 la voix d\u2019or du fiston Tristan, quelques fen\u00eatres lui sont bien entendu ouvertes, comme sur \u00ab&nbsp;Quasimodo&nbsp;\u00bb et plus particuli\u00e8rement sur le tr\u00e8s emphatique \u00ab&nbsp;Harmonie&nbsp;\u00bb. S\u2019ils sont plus discrets, les trois autres lascars (Beno\u00eet Cazzulini, Thierry Sidhoum et l\u2019in\u00e9narrable Hassan Hajdi) constituent un pilier musical ind\u00e9fectible. <\/p>\n<p>  <img loading=\"lazy\" alt=\"\" src=\"\/images\/contenu\/articles\/old\/live_ange09_3.jpg\" width=\"150\" height=\"150\" align=\"right\" border=\"1\">Le show, tr\u00e8s dynamique, use de nombreux artifices : jeu de lumi\u00e8re, costumes, accessoires (de la marionnette-squelette au lance-pierre !)\u2026 Les moments forts sont nombreux, mais retenons plus particuli\u00e8rement l\u2019interpr\u00e9tation de \u00ab&nbsp;Souffleurs de vers&nbsp;\u00bb, qui conna\u00eet sur sc\u00e8ne une v\u00e9ritable transfiguration et s\u2019affirme d\u00e9j\u00e0 comme un incontournable des concerts d\u2019Ange. La mise en sc\u00e8ne de ce conte futuriste original, la puissance \u00e9vocatrice de sa musique et les atmosph\u00e8res envo\u00fbtantes qui l\u2019habitent, font de ce titre \u00e9pique un v\u00e9ritable \u00e9v\u00e9nement audiovisuel, o\u00f9 Caroline Crozat, en narratrice poss\u00e9d\u00e9e, tisse le fil conducteur d\u2019une passionnante \u00e9pop\u00e9e. <\/p>\n<p>  <img loading=\"lazy\" alt=\"\" src=\"\/images\/contenu\/articles\/old\/live_ange09_5.jpg\" width=\"220\" height=\"150\" align=\"left\" border=\"1\">Comme dans toute Convention qui se respecte, quelques bonus viennent agr\u00e9menter le concert. Sur \u00ab&nbsp;Catiline&nbsp;\u00bb et \u00ab&nbsp;Juste une ligne bleue&nbsp;\u00bb , une paire d\u2019ex-membres, en les personnes de Herv\u00e9 Rouyer (batterie) et Jean-Pascal Boffo (guitare) viennent pr\u00eater main forte \u00e0 une troupe qui a connu bien des incarnations depuis le d\u00e9but des ann\u00e9es soixante-dix. Et les fans ne sont pas en reste : ici, un jeune batteur monte sur sc\u00e8ne accompagner ses idoles, l\u00e0, un autre \u00ab&nbsp;imbib\u00e9&nbsp;\u00bb (c\u2019est ainsi que sont appel\u00e9s les membres du fan-club !) vient d\u00e9clamer une po\u00e9sie touchante en hommage \u00e0 sa grand-m\u00e8re. Puis, c\u2019est \u00e0 l\u2019\u00e9quipe d\u2019UPDLM de se retrouver sur sc\u00e8ne, chorale h\u00e9t\u00e9roclite accompagnant le patriarche sur un joyeux final. <\/p>\n<p>  La bonne humeur perdure tandis que la foule se disperse. On \u00e9change, on commente, on ach\u00e8te un disque, un tee-shirt. Dans l\u2019\u0153il du public, on lit la satisfaction, le plaisir de s\u2019\u00eatre retrouv\u00e9 entre privil\u00e9gi\u00e9s pour un moment magique, en compagnie d\u2019un groupe quadrag\u00e9naire. Dans la force de l\u2019\u00e2ge.         <\/p>\n<p align=\"right\" class=\"dateconcert\"><strong>Jean-Philippe Haas<br \/>       <\/strong><\/p>\n<p align=\"center\" class=\"dateconcert\"><strong>site web : <\/strong><a href=\"http:\/\/angemusic.free.fr\" target=\"_blank\" class=\"dateconcert\"><font color=\"#0000FF\"><strong>Ange<\/strong><\/font><\/a><\/p>\n<p align=\"center\" class=\"dateconcert\"><strong><a href=\"http:\/\/http:\/\/www.chromatique.net\/index.php?option=com_k2&#038;view=itemlist&#038;layout=category&#038;task=category&#038;id=2&#038;Itemid=4\"><font color=\"#CA0B4E\"><font color=\"#157175\">retour          au sommaire<\/font><\/font><\/a><\/strong><\/p>\n<\/td>\n<\/tr>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>CONCERT : ANGE &nbsp; Lieu : G\u00e9rardmer, Espace LAC Date : 09 mai 2009 Photos&#8230;<\/p>\n","protected":false},"author":14,"featured_media":18103,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/18102"}],"collection":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/comments?post=18102"}],"version-history":[{"count":0,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/posts\/18102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media\/18103"}],"wp:attachment":[{"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/media?parent=18102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/categories?post=18102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chromatique.net\/index.php\/wp-json\/wp\/v2\/tags?post=18102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}